{"id":88821,"date":"2026-04-30T19:54:57","date_gmt":"2026-04-30T19:54:57","guid":{"rendered":"https:\/\/degreed.com\/experience\/?p=88821"},"modified":"2026-05-12T22:41:02","modified_gmt":"2026-05-12T22:41:02","slug":"pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot","status":"publish","type":"post","link":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/","title":{"rendered":"So bringt Pernod Ricard Skillentwicklung und Gesch\u00e4ftsstrategie ins Lot"},"content":{"rendered":"\n<p>Wenn es um die \u00fcbergeordnete Gesch\u00e4ftsstrategie ging, spielte Lernen lange Zeit eine eher untergeordnete Rolle. Mit dem Vormarsch von KI haben die bisherigen Regeln der Gesch\u00e4ftswelt jedoch keine G\u00fcltigkeit mehr.<\/p>\n\n\n\n<p>In den meisten Unternehmen wurde Lernen und Personalentwicklung stets als unterst\u00fctzende Funktion betrachtet&nbsp;\u2013 und dies gilt auch heute zumeist noch. Man sah (oder sieht) darin einen Bereich, f\u00fcr den die Personalabteilung zust\u00e4ndig ist, mit dem Mitarbeitende sich bei Bedarf besch\u00e4ftigen und dessen Erfolg anhand der Anzahl durchgearbeiteter Inhalte gemessen wird.<\/p>\n\n\n\n<p>In der Welt von heute ist der Kompetenzaufbau jedoch unerl\u00e4sslich, um mit dem Wandel Schritt zu halten.<\/p>\n\n\n\n<p>Um sich besser daf\u00fcr aufzustellen, wollte Pernod Ricard neue Wege gehen, indem das Unternehmen Lernen zum Motor seiner gesch\u00e4ftlichen Transformation und in diesem Zuge Skilldaten zu einem seiner wertvollsten strategischen Verm\u00f6genswerte machte.<\/p>\n\n\n\n<p>Auf der Degreed LENS gaben <a href=\"https:\/\/www.linkedin.com\/in\/louis-bosche-2aa26955\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Louis Bosche<\/a>, Head of HR Tech, und <a href=\"https:\/\/www.linkedin.com\/in\/anna-gosteva\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Anna Gosteva<\/a>, Product Owner for Learning and Engagement Solutions, Einblicke dazu, wie Pernod Ricard ein skillorientiertes \u00d6kosystem aufgebaut hat, das heute auf Entscheidungsprozesse des Unternehmens Einfluss nimmt, die weit \u00fcber den Bereich L&D hinausgehen&nbsp;\u2013 von der Talentakquise und internen Mobilit\u00e4t bis hin zur Personalplanung und der Unternehmensstrategie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-mitarbeitertransformation-als-mandat\">Mitarbeitertransformation als Mandat<\/h2>\n\n\n\n<p>Der Spirituosenhersteller, der weltweit 150 Marken in sich vereint (darunter Jameson, Chivas, Ballantine\u2019s und Absolut), sah sich zunehmend mit Herausforderungen konfrontiert: Rasante Ver\u00e4nderungen der Verbrauchererwartungen in den Kernm\u00e4rkten erforderten es, die Arbeitsweise der Marketing-, Vertriebs- und Produktteams grundlegend neu auszurichten. Um Inflation und regulatorische \u00c4nderungen Rechnung zu tragen, bedurfte es zudem einer Umgestaltung der weltweiten Gesch\u00e4ftsabl\u00e4ufe. Eine zentrale Rolle kam der Resilienz der Lieferkette zu, au\u00dferdem galt es im Sinne der Wirtschaftlichkeit, die Kosteneffizienz in globalem Ma\u00dfstab zu steigern.<\/p>\n\n\n\n<p>Mehr denn je hing die Wettbewerbsf\u00e4higkeit des Pernod Ricard-Teams davon ab, die richtigen F\u00e4higkeiten zur richtigen Zeit am richtigen Ort bereitzustellen.<\/p>\n\n\n\n<p> \u201ePr\u00e4gend f\u00fcr unsere Branche ist, dass sie sich ununterbrochen ver\u00e4ndert\u201c, erkl\u00e4rt Bosche. \u201eUmso wichtiger ist es, dass wir unseren Mitarbeitenden diese Ver\u00e4nderungen schnell vermitteln. Dazu ben\u00f6tigen wir Klarheit dar\u00fcber, wo sie aktuell stehen und \u00fcber welche F\u00e4higkeiten sie verf\u00fcgen, damit wir sie in die Zukunft f\u00fchren k\u00f6nnen.\u201c<\/p>\n\n\n\n<p>Der Handlungsdruck, dem sich Pernod Ricard ausgesetzt sieht, spiegelt die Situation in fast jedem Unternehmen wider. Denn wie Untersuchungen zeigen, werden sich <a href=\"https:\/\/www.weforum.org\/publications\/the-future-of-jobs-report-2023\/digest\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">44&nbsp;% der Skills, \u00fcber die Mitarbeitenden heute verf\u00fcgen,<\/a> bis 2027 ver\u00e4ndern m\u00fcssen&nbsp;\u2013 und dass den Unternehmen die Zeit davonl\u00e4uft, sich auf diese Realit\u00e4t einzustellen. &nbsp;<\/p>\n\n\n\n<p>Bei Pernod Ricard kamen zudem interne Faktoren zum Tragen, die Ver\u00e4nderungen erforderten.&nbsp;So hatte eine Mitarbeiterumfrage ergeben, dass 95&nbsp;% der Besch\u00e4ftigten l\u00e4nger bei einem Unternehmen bleiben w\u00fcrden, das in ihre berufliche Weiterentwicklung investiert, was einen direkten Zusammenhang zwischen Investitionen in Weiterbildung und Mitarbeiterbindung herstellt. Eine zentrale Bedeutung ma\u00dfen die Mitarbeitenden zudem ihren M\u00f6glichkeiten zum Lernen zu.<\/p>\n\n\n\n<p>Dazu mussten sie bis dato jedoch auf ein Lernsystem zur\u00fcckgreifen, das dringender Modernisierungen bedurfte: Eine Vielzahl sich \u00fcberschneidender Plattformen und diverse redundante Tools bildeten ein komplexes Geflecht, das zu \u00fcberh\u00f6hten Kosten f\u00fchrte. Das \u00d6kosystem war so fragmentiert, dass man es kaum noch als solches bezeichnen konnte.<\/p>\n\n\n\n<p>Dass etwas getan musste, war klar. Die Frage war nur, wie man dabei vorgehen sollte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-skills-als-universelle-sprache-fur-pernod-ricard\">Skills als universelle Sprache f\u00fcr Pernod Ricard<\/h2>\n\n\n\n<p>Anstatt ein weiteres Schulungsprogramm ins Leben zu rufen, setzte Pernod Ricard darauf, eine Grundlage f\u00fcr Skills zu schaffen. Dies beinhaltete die Einf\u00fchrung eines Skillkatalogs f\u00fcr rund 900 Jobrollen, ordnete jedem Profil etwa 20 Kompetenzen zu und integrierte diese direkt in Workday, das globale HRIS des Unternehmens.<\/p>\n\n\n\n<p>Dies galt einem klaren Ziel: Skills sollten die universelle Sprache zur Beschreibung von F\u00e4higkeiten werden, die individuelle Entwicklung und gesch\u00e4ftliche Ergebnisse auf eine Linie bringt.&nbsp;<\/p>\n\n\n\n<p>Hierzu entwickelte das Team eine technische Architektur, die das Management von Lerninhalten und die entsprechenden Tools optimieren und gleichzeitig die Skilldaten system\u00fcbergreifend zusammenf\u00fchren sollte. &nbsp;<\/p>\n\n\n\n<p>Mitarbeitende konnten ihre Skills angeben, Karrierem\u00f6glichkeiten identifizieren, an skillbasierten Mentoring-Programmen teilnehmen und sich f\u00fcr interne \u201eGigs\u201c bewerben&nbsp;\u2013 also kurzfristige Eins\u00e4tze, bei denen sie neue F\u00e4higkeiten erwerben und gleichzeitig in verschiedenen Bereichen des Unternehmens einen Beitrag leisten konnten. Seit der Einf\u00fchrung haben mehr als 70&nbsp;% der Mitarbeitenden 15 oder mehr Skills in Workday angegeben, darunter auch solche aus operativen Bereichen, die bisher schwerer zu erreichen waren.<\/p>\n\n\n\n<p>Das Unternehmen traf zudem fr\u00fchzeitig eine Entscheidung, die alles Weitere pr\u00e4gte: Skilldaten sollten zur Personalentwicklung und Erschlie\u00dfung neuer Chancen genutzt werden, jedoch niemals f\u00fcr Leistungsbeurteilungen oder Verg\u00fctungsentscheidungen.&nbsp;<\/p>\n\n\n\n<p>Diese Entscheidung schuf Vertrauen, und dieses Vertrauen trieb die breite Akzeptanz voran.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Explore Pernod Ricard\u2019s Skills-Based Ecosystem with Degreed + HRIS\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/d9WX3spSUXA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Skills, Systeme und Unternehmensstrategie in Einklang<\/h2>\n\n\n\n<p>Mit der Einf\u00fchrung seines auf Degreed gest\u00fctzten Lern-Hubs l\u00f6ste Pernod Ricard nicht nur ein technologisches Problem. Denn damit entstand auch eine direkte Verbindung zwischen Lerninitiativen und der Gesch\u00e4ftsstrategie.<\/p>\n\n\n\n<p>Ausdruck fand diese Verbindung ganz konkret in f\u00fcnf vom Unternehmen priorisierten, bereichs\u00fcbergreifenden F\u00fchrungskompetenzen, die als entscheidend f\u00fcr jeden Mitarbeiter identifiziert wurden&nbsp;\u2013 unabh\u00e4ngig von Funktion oder Hierarchiestufe. Dabei handelt es sich nicht um generische Themen zu beruflicher Weiterentwicklung. Vielmehr passen sie sich exakt in das ein, was Pernod Ricard unternehmensweit ben\u00f6tigt, um seine Gesch\u00e4ftsstrategie umzusetzen:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Gesch\u00e4ftliche Versiertheit<\/li>\n\n\n\n<li>Generative KI<\/li>\n\n\n\n<li>Lebenslanges Lernen<\/li>\n\n\n\n<li>\u00c4nderungsmanagement<\/li>\n\n\n\n<li>Inklusives Handeln<\/li>\n<\/ol>\n\n\n\n<p>\u201eDiese Initiative zum Skillaufbau kann als Motor f\u00fcr das Wachstum unseres Unternehmens fungieren\u201c, so Gosteva. \u201eWir \u00fcberlegten uns, wie wir durch unsere Upskilling-Initiative die gesch\u00e4ftliche Transformation vorantreiben und unsere Gesch\u00e4ftsziele erreichen k\u00f6nnen.\u201c<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/04\/Anna-Gosteva-Pernod-Ricard.jpg\" alt=\"Anna Gosteva, Pernod Ricard\" class=\"wp-image-88754\"\/><\/figure>\n\n\n\n<p>Das neu integrierte \u00d6kosystem hat dies noch verst\u00e4rkt. Indem das Unternehmen diverse lokale Plattformen ausrangierte und durch Degreed ersetzte, lie\u00dfen sich Einsparungen in H\u00f6he von 600.000&nbsp;Euro realisieren. Nun fungiert Degreed als zentrale Anlaufstelle, \u00fcber die Mitarbeitende auf Weiterbildungsangebote zugreifen k\u00f6nnen, die direkt auf ihr Skillprofil und ihren Lernfortschritt abgestimmt sind.&nbsp;<\/p>\n\n\n\n<p>Es entstanden zudem ein deutlich verbessertes Lernerlebnis und ein nahtloses Daten\u00f6kosystem. Skillbeurteilungen werden bidirektional zwischen Degreed und Workday ausgetauscht. Dadurch werden die Daten in Echtzeit aktualisiert, sobald Mitarbeitende ein h\u00f6heres Leistungsniveau nachweisen, und f\u00fcr Personalentscheidungen im gesamten Unternehmen zur Verf\u00fcgung gestellt.&nbsp;<\/p>\n\n\n\n<p>Das Unternehmen hat sich zudem dazu verpflichtet, jedem Mitarbeiter eine Stunde Weiterbildung pro Woche zu gew\u00e4hren \u2013 doppelt so viel wie der Branchenstandard. Diese Ma\u00dfnahme wird von der Unternehmensleitung unterst\u00fctzt und ist fest in der Unternehmensf\u00fchrung und den Arbeitsabl\u00e4ufen verankert.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Skilldaten als strategischer Gesch\u00e4ftsfaktor<\/h2>\n\n\n\n<p>Die Resonanz vonseiten der Mitarbeitenden war bereits ein enormer Erfolg. Beinahe noch mehr profitiert Pernod Ricard aber von der ausgedehnten Nutzung von Skilldaten.<\/p>\n\n\n\n<p>\u201eUnser CIO, unser CHRO und alle F\u00fchrungskr\u00e4fte fragen uns: Wann erhalte ich Zugriff auf Skilldaten meiner Mitarbeitenden?\u201c, kommentiert Bosche.  \u201eKann ich erfahren, wer \u00fcber welche Skills verf\u00fcgt, auf welchem Leistungsniveau diese liegen und wo L\u00fccken bestehen? Denn sie wissen, dass dies \u00e4u\u00dferst interessante Erkenntnisse w\u00e4ren, die es zu verstehen gilt.\u201c<\/p>\n\n\n\n<p>Dieses Ergebnis verdeutlicht eindrucksvoll den Wert von Investitionen in die betriebliche Weiterbildung.&nbsp;<\/p>\n\n\n\n<p>Wenn Skill-Intelligence nicht mehr nur im L&D-Dashboard verbleibt, sondern den F\u00fchrungskr\u00e4ften in den Gesch\u00e4ftsbereichen zur Verf\u00fcgung steht, kann sie die Personalplanung und interne Personalbeschaffung ebenso unterst\u00fctzen wie die Gestaltung der Organisation.&nbsp;<\/p>\n\n\n\n<p>Pernod Ricard nutzt Daten zum Skill-Leistungsniveau, um Kompetenzl\u00fccken auf geografischer Ebene zu identifizieren und Lerninvestitionen mithilfe von Skill-Heatmaps gezielter auszurichten. Dar\u00fcber hinaus hilft KI-gest\u00fctzter Skillabgleich dabei, die Personalbeschaffung gezielt zu verbessern. So l\u00e4sst sich die Abh\u00e4ngigkeit von externen Einstellungen reduzieren, indem interne Talente f\u00fcr entsprechende Positionen weiterentwickelt werden.<\/p>\n\n\n\n<p>Der Lern-Hub bietet den L&D-Verantwortlichen zudem etwas, was ihnen bisher gefehlt hat: eine datengest\u00fctzte \u00dcbersicht dar\u00fcber, wo Investitionen get\u00e4tigt werden sollten. Daten zum Skillangebot und zum Lernfortschritt flie\u00dfen nun in Entscheidungen zum Kauf von Lerninhalten, in die Gestaltung von Upskilling-Programmen und in die Entwicklung funktionsspezifischer Akademien ein.<\/p>\n\n\n\n<p>\u201eSkills sind nicht nur ein Thema f\u00fcr die Personalabteilung\u201c, so Bosche. \u201eVielmehr sind sie ein Thema f\u00fcr das gesamte Unternehmen.\u201c<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/04\/Louis-Bosche-Pernod-Ricard.jpg\" alt=\"Louis Bosche, Pernod Ricard\" class=\"wp-image-88759\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Ihr Weg zur skillorientierten Organisation<\/h2>\n\n\n\n<p>Am Beispiel von Pernod Ricard zeigt sich eindrucksvoll, wie Unternehmen aller Art \u00fcber die Messung der Lernbeteiligung hinausgehen und sinnvolle Gesch\u00e4ftsergebnisse erzielen k\u00f6nnen.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Beginnen Sie mit einer Skillarchitektur, die im gesamten Unternehmen genutzt werden kann.&nbsp;<\/li>\n\n\n\n<li>Verbinden Sie diese Architektur direkt mit den gesch\u00e4ftlichen Priorit\u00e4ten, so wie die f\u00fcnf \u00fcbergreifenden Skills von Pernod Ricard mit der Unternehmensstrategie verkn\u00fcpft sind.&nbsp;<\/li>\n\n\n\n<li>Schaffen Sie ein integriertes \u00d6kosystem, in dem Skilldaten system\u00fcbergreifend \u00fcbergeben werden und so zur Entscheidungsfindung auf allen Ebenen beitragen k\u00f6nnen.&nbsp;<\/li>\n\n\n\n<li>Bieten Sie F\u00fchrungskr\u00e4ften aus dem operativen Gesch\u00e4ft&nbsp;\u2013 und nicht nur der Personalabteilung&nbsp;\u2013 Zugang zu den Erkenntnissen, die das \u00d6kosystem generiert.<\/li>\n<\/ol>\n\n\n\n<p>All diese Schritte f\u00fchren zu messbarem gesch\u00e4ftlichen Erfolg. Das ist das eigentliche Versprechen einer Unternehmenskultur, die Skills in den Mittelpunkt stellt. Es geht nicht darum, Inhalte zu erledigen, sondern gesch\u00e4ftliche Ergebnisse zu liefern.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"150\" src=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/04\/Start-your-skills-first-journey_DE-DE.png\" alt=\"\" class=\"wp-image-88844\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Wenn es um die \u00fcbergeordnete Gesch\u00e4ftsstrategie ging, spielte Lernen lange Zeit eine eher untergeordnete Rolle. Mit dem Vormarsch von KI haben die bisherigen Regeln der Gesch\u00e4ftswelt jedoch keine G\u00fcltigkeit mehr. In den meisten Unternehmen wurde Lernen und Personalentwicklung stets als unterst\u00fctzende Funktion betrachtet&nbsp;\u2013 und dies gilt auch heute zumeist noch. Man sah (oder sieht) darin [&hellip;]<\/p>\n","protected":false},"author":141,"featured_media":88751,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[652],"tags":[],"post_folder":[],"class_list":["post-88821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-skills-talent-mobility"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>So bringt Pernod Ricard Skillentwicklung und Gesch\u00e4ftsstrategie ins Lot - Degreed<\/title>\n<meta name=\"description\" content=\"In puncto Skills geht es nicht um Personalfragen, sondern um gesch\u00e4ftlichen Erfolg. Pernod Ricard hat das erkannt\u00a0\u2013 und in ein Konzept \u00fcberf\u00fchrt, das Qualifikationsl\u00fccken sichtbar und personelle Transformation umsetzbar macht. Wie, das erfahren Sie hier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"So bringt Pernod Ricard Skillentwicklung und Gesch\u00e4ftsstrategie ins Lot\" \/>\n<meta property=\"og:description\" content=\"In puncto Skills geht es nicht um Personalfragen, sondern um gesch\u00e4ftlichen Erfolg. Pernod Ricard hat das erkannt\u00a0\u2013 und in ein Konzept \u00fcberf\u00fchrt, das Qualifikationsl\u00fccken sichtbar und personelle Transformation umsetzbar macht. Wie, das erfahren Sie hier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/\" \/>\n<meta property=\"og:site_name\" content=\"Degreed\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DegreedOfficial\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-30T19:54:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T22:41:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/04\/pernod-ricard-business-strategy.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Patricia Gallagher\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@degreed\" \/>\n<meta name=\"twitter:site\" content=\"@degreed\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Patricia Gallagher\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/blog\\\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/blog\\\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\\\/\"},\"author\":{\"name\":\"Patricia Gallagher\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/#\\\/schema\\\/person\\\/71256d17ecd63413bf343ad986681018\"},\"headline\":\"So bringt Pernod Ricard Skillentwicklung und Gesch\u00e4ftsstrategie ins Lot\",\"datePublished\":\"2026-04-30T19:54:57+00:00\",\"dateModified\":\"2026-05-12T22:41:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/blog\\\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\\\/\"},\"wordCount\":1505,\"publisher\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/blog\\\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pernod-ricard-business-strategy.png\",\"articleSection\":[\"Skills und Talentmobilit\u00e4t\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/blog\\\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\\\/\",\"url\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/blog\\\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\\\/\",\"name\":\"So bringt Pernod Ricard Skillentwicklung und Gesch\u00e4ftsstrategie ins Lot - Degreed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/blog\\\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/blog\\\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pernod-ricard-business-strategy.png\",\"datePublished\":\"2026-04-30T19:54:57+00:00\",\"dateModified\":\"2026-05-12T22:41:02+00:00\",\"description\":\"In puncto Skills geht es nicht um Personalfragen, sondern um gesch\u00e4ftlichen Erfolg. Pernod Ricard hat das erkannt\u00a0\u2013 und in ein Konzept \u00fcberf\u00fchrt, das Qualifikationsl\u00fccken sichtbar und personelle Transformation umsetzbar macht. Wie, das erfahren Sie hier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/blog\\\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/blog\\\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/blog\\\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\\\/#primaryimage\",\"url\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pernod-ricard-business-strategy.png\",\"contentUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/pernod-ricard-business-strategy.png\",\"width\":1200,\"height\":1200,\"caption\":\"Pernord Ricard LENS 2026\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/blog\\\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"So bringt Pernod Ricard Skillentwicklung und Gesch\u00e4ftsstrategie ins Lot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/\",\"name\":\"Degreed\",\"description\":\"The Learning and Upskilling Platform\",\"publisher\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/#organization\",\"name\":\"Degreed\",\"url\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo.svg\",\"caption\":\"Degreed\"},\"image\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DegreedOfficial\",\"https:\\\/\\\/x.com\\\/degreed\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/degreed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkH3pyPKVngvsZzZlmoH-Mw\",\"https:\\\/\\\/www.instagram.com\\\/degreed\\\/\"],\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"201\",\"maxValue\":\"500\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/de\\\/#\\\/schema\\\/person\\\/71256d17ecd63413bf343ad986681018\",\"name\":\"Patricia Gallagher\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/degreed-blog-1.png\",\"url\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/degreed-blog-1.png\",\"contentUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/degreed-blog-1.png\",\"caption\":\"Patricia Gallagher\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"So bringt Pernod Ricard Skillentwicklung und Gesch\u00e4ftsstrategie ins Lot - Degreed","description":"In puncto Skills geht es nicht um Personalfragen, sondern um gesch\u00e4ftlichen Erfolg. Pernod Ricard hat das erkannt\u00a0\u2013 und in ein Konzept \u00fcberf\u00fchrt, das Qualifikationsl\u00fccken sichtbar und personelle Transformation umsetzbar macht. Wie, das erfahren Sie hier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/","og_locale":"de_DE","og_type":"article","og_title":"So bringt Pernod Ricard Skillentwicklung und Gesch\u00e4ftsstrategie ins Lot","og_description":"In puncto Skills geht es nicht um Personalfragen, sondern um gesch\u00e4ftlichen Erfolg. Pernod Ricard hat das erkannt\u00a0\u2013 und in ein Konzept \u00fcberf\u00fchrt, das Qualifikationsl\u00fccken sichtbar und personelle Transformation umsetzbar macht. Wie, das erfahren Sie hier.","og_url":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/","og_site_name":"Degreed","article_publisher":"https:\/\/www.facebook.com\/DegreedOfficial","article_published_time":"2026-04-30T19:54:57+00:00","article_modified_time":"2026-05-12T22:41:02+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/04\/pernod-ricard-business-strategy.png","type":"image\/png"}],"author":"Patricia Gallagher","twitter_card":"summary_large_image","twitter_creator":"@degreed","twitter_site":"@degreed","twitter_misc":{"Verfasst von":"Patricia Gallagher","Gesch\u00e4tzte Lesezeit":"9 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/#article","isPartOf":{"@id":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/"},"author":{"name":"Patricia Gallagher","@id":"https:\/\/degreed.com\/experience\/de\/#\/schema\/person\/71256d17ecd63413bf343ad986681018"},"headline":"So bringt Pernod Ricard Skillentwicklung und Gesch\u00e4ftsstrategie ins Lot","datePublished":"2026-04-30T19:54:57+00:00","dateModified":"2026-05-12T22:41:02+00:00","mainEntityOfPage":{"@id":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/"},"wordCount":1505,"publisher":{"@id":"https:\/\/degreed.com\/experience\/de\/#organization"},"image":{"@id":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/#primaryimage"},"thumbnailUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/04\/pernod-ricard-business-strategy.png","articleSection":["Skills und Talentmobilit\u00e4t"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/","url":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/","name":"So bringt Pernod Ricard Skillentwicklung und Gesch\u00e4ftsstrategie ins Lot - Degreed","isPartOf":{"@id":"https:\/\/degreed.com\/experience\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/#primaryimage"},"image":{"@id":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/#primaryimage"},"thumbnailUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/04\/pernod-ricard-business-strategy.png","datePublished":"2026-04-30T19:54:57+00:00","dateModified":"2026-05-12T22:41:02+00:00","description":"In puncto Skills geht es nicht um Personalfragen, sondern um gesch\u00e4ftlichen Erfolg. Pernod Ricard hat das erkannt\u00a0\u2013 und in ein Konzept \u00fcberf\u00fchrt, das Qualifikationsl\u00fccken sichtbar und personelle Transformation umsetzbar macht. Wie, das erfahren Sie hier.","breadcrumb":{"@id":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/#primaryimage","url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/04\/pernod-ricard-business-strategy.png","contentUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/04\/pernod-ricard-business-strategy.png","width":1200,"height":1200,"caption":"Pernord Ricard LENS 2026"},{"@type":"BreadcrumbList","@id":"https:\/\/degreed.com\/experience\/de\/blog\/pernod-ricard-bringt-skillentwicklung-und-geschaeftsstrategie-ins-lot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/degreed.com\/experience\/de\/"},{"@type":"ListItem","position":2,"name":"So bringt Pernod Ricard Skillentwicklung und Gesch\u00e4ftsstrategie ins Lot"}]},{"@type":"WebSite","@id":"https:\/\/degreed.com\/experience\/de\/#website","url":"https:\/\/degreed.com\/experience\/de\/","name":"Degreed","description":"The Learning and Upskilling Platform","publisher":{"@id":"https:\/\/degreed.com\/experience\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/degreed.com\/experience\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/degreed.com\/experience\/de\/#organization","name":"Degreed","url":"https:\/\/degreed.com\/experience\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/degreed.com\/experience\/de\/#\/schema\/logo\/image\/","url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2023\/05\/logo.svg","contentUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2023\/05\/logo.svg","caption":"Degreed"},"image":{"@id":"https:\/\/degreed.com\/experience\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DegreedOfficial","https:\/\/x.com\/degreed","https:\/\/www.linkedin.com\/company\/degreed\/","https:\/\/www.youtube.com\/channel\/UCkH3pyPKVngvsZzZlmoH-Mw","https:\/\/www.instagram.com\/degreed\/"],"numberOfEmployees":{"@type":"QuantitativeValue","minValue":"201","maxValue":"500"}},{"@type":"Person","@id":"https:\/\/degreed.com\/experience\/de\/#\/schema\/person\/71256d17ecd63413bf343ad986681018","name":"Patricia Gallagher","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/degreed-blog-1.png","url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/degreed-blog-1.png","contentUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/degreed-blog-1.png","caption":"Patricia Gallagher"}}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/explore.degreed.com\/experience\/de\/wp-json\/wp\/v2\/posts\/88821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explore.degreed.com\/experience\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explore.degreed.com\/experience\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/de\/wp-json\/wp\/v2\/users\/141"}],"replies":[{"embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/de\/wp-json\/wp\/v2\/comments?post=88821"}],"version-history":[{"count":0,"href":"https:\/\/explore.degreed.com\/experience\/de\/wp-json\/wp\/v2\/posts\/88821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/de\/wp-json\/wp\/v2\/media\/88751"}],"wp:attachment":[{"href":"https:\/\/explore.degreed.com\/experience\/de\/wp-json\/wp\/v2\/media?parent=88821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/de\/wp-json\/wp\/v2\/categories?post=88821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/de\/wp-json\/wp\/v2\/tags?post=88821"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/de\/wp-json\/wp\/v2\/post_folder?post=88821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}