{"id":63820,"date":"2021-01-06T16:12:00","date_gmt":"2021-01-06T16:12:00","guid":{"rendered":"https:\/\/explore.local\/blog-archive\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/"},"modified":"2026-03-29T06:41:47","modified_gmt":"2026-03-29T06:41:47","slug":"les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise","status":"publish","type":"post","link":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/","title":{"rendered":"Les nouveaux indicateurs de la formation : d\u00e9montrer l\u2019impact et la valeur ajout\u00e9e pour l\u2019entreprise"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Pour attirer l\u2019attention de votre direction et faire de votre programme de formation une priorit\u00e9 strat\u00e9gique, vous pouvez relater votre exp\u00e9rience en mati\u00e8re de perfectionnement des effectifs de mani\u00e8re originale, en vous appuyant sur de nouveaux indicateurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00eame si votre programme est d\u00e9j\u00e0 une priorit\u00e9, vous avez un r\u00e9cit \u00e0 livrer, qui permettra de renforcer la valeur et l\u2019impact de la formation, du d\u00e9veloppement des comp\u00e9tences et de la mobilit\u00e9 interne, qui sont des facteurs d\u00e9terminants dans la r\u00e9alisation des objectifs les plus importants de votre entreprise. Vous pourrez ainsi d\u00e9montrer que les investissements dans les ressources humaines peuvent vous aider \u00e0 les atteindre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De nombreuses organisations sont confront\u00e9es \u00e0 une urgence imm\u00e9diate. La U.S. Securities and Exchange Commission <a href=\"https:\/\/www.chieflearningofficer.com\/2020\/11\/05\/the-sec-just-mandated-human-capital-disclosure-what-does-this-mean-for-you\/\" target=\"_blank\" rel=\"noreferrer noopener\">a r\u00e9cemment rendu obligatoire la divulgation d\u2019informations sur le capital humain<\/a> par toutes les soci\u00e9t\u00e9s cot\u00e9es en bourse aux \u00c9tats-Unis. Cette mesure est entr\u00e9e en vigueur en novembre et devrait finir par \u00eatre appliqu\u00e9e aux soci\u00e9t\u00e9s priv\u00e9es ainsi qu\u2019aux organisations \u00e0 but non lucratif, si bien que les directeurs financiers et les responsables des ressources humaines auront besoin de conna\u00eetre les donn\u00e9es \u00ab&nbsp;essentielles pour l\u2019entreprise&nbsp;\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ce sont les d\u00e9tails qui font la qualit\u00e9 du r\u00e9cit<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les bons indicateurs, \u00e0 savoir les donn\u00e9es qui permettent de mesurer la r\u00e9ussite au-del\u00e0 des m\u00e9thodes de L&D traditionnelles, peuvent donner plus de poids \u00e0 votre nouveau r\u00e9cit sur la formation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans leur livre intitul\u00e9 <a href=\"https:\/\/www.expertiseeconomy.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>The Expertise Economy<\/em><\/a>, Kelly Palmer, CLO de Degreed, et David Blake, son cofondateur, attirent l\u2019attention sur le fait que la formation en entreprise est souvent consid\u00e9r\u00e9e comme un poste de d\u00e9penses plut\u00f4t que comme une source de revenus. \u00ab&nbsp;La formation devient g\u00e9n\u00e9ralement <a href=\"https:\/\/degreed.com\/experience\/fr\/blog\/6-steps-to-align-ld-with-your-business\/\" target=\"_blank\" rel=\"noreferrer noopener\">plus r\u00e9active que strat\u00e9gique<\/a>. Par exemple, certains dirigeants d\u2019entreprises veulent un programme de formation sur les pr\u00e9jug\u00e9s conscients, quand d\u2019autres souhaitent une formation sur le d\u00e9veloppement agile, et d\u2019autres encore un programme d\u2019int\u00e9gration.&nbsp;\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme le soulignent Palmer et Blake, \u00ab&nbsp;un bon responsable de la formation qui comprend bien les besoins de l\u2019entreprise peut \u00e9laborer une strat\u00e9gie reposant sur des donn\u00e9es provenant de plusieurs sources et d\u00e9montrer que celle-ci peut avoir un impact significatif sur l\u2019entreprise et les collaborateurs.&nbsp;\u00bb<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Jusqu\u2019\u00e0 pr\u00e9sent&nbsp;: les indicateurs essentiels pour la formation<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous \u00eates comme de nombreux professionnels des services&nbsp;RH, des carri\u00e8res et de la formation, vous avez \u00e0 c\u0153ur de favoriser le d\u00e9veloppement des \u00e9quipes en vous appuyant davantage sur les donn\u00e9es et la strat\u00e9gie afin de prendre des d\u00e9cisions et de r\u00e9aliser des investissements qui produisent des r\u00e9sultats.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www2.deloitte.com\/us\/en\/insights\/topics\/analytics\/insight-driven-organization.html\" target=\"_blank\" rel=\"noreferrer noopener\">D\u2019apr\u00e8s une \u00e9tude de Deloitte<\/a>, les dirigeants et les chefs d\u2019entreprise souhaitent que leurs \u00e9quipes soient guid\u00e9es par des outils d\u2019analyse avanc\u00e9s. Dans cette m\u00eame \u00e9tude, les organisations ayant d\u00e9clar\u00e9 \u00eatre les plus favorables aux orientations et \u00e0 la prise de d\u00e9cision bas\u00e9es sur les donn\u00e9es \u00e9taient deux&nbsp;fois plus susceptibles de d\u00e9clarer avoir d\u00e9pass\u00e9 leurs objectifs commerciaux au cours des 12&nbsp;mois pr\u00e9c\u00e9dents. Les conclusions du nouveau rapport de Degreed \u00ab&nbsp;<a href=\"https:\/\/get.degreed.com\/fr\/state-of-skills-lp-france\" target=\"_blank\" rel=\"noreferrer noopener\">L\u2019\u00e9tat des comp\u00e9tences&nbsp;2021<\/a>&nbsp;\u00bb montrent que les professionnels des RH classent l\u2019analyse avanc\u00e9e des donn\u00e9es parmi les dix&nbsp;comp\u00e9tences les plus recherch\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cependant, les indicateurs traditionnels de la formation, comme le nombre de cours effectivement suivis et les heures de formation, ne suffisent souvent pas \u00e0 convaincre les PDG, les dirigeants d\u2019entreprise, les managers, les collaborateurs individuels ou autres des avantages de la formation. Combin\u00e9s \u00e0 des indices d\u2019efficacit\u00e9 tels que les heures de formation consomm\u00e9es par collaborateur, le co\u00fbt de la formation par heure, les ratios personnel\/collaborateurs et vos diff\u00e9rentes modalit\u00e9s, ces indicateurs peuvent donner un bref aper\u00e7u de la mani\u00e8re dont vos collaborateurs interagissent avec vos programmes de formation. Cependant, ils ne permettent pas de prouver qu\u2019ils ont r\u00e9ellement appris quelque chose.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les enqu\u00eates aupr\u00e8s des employ\u00e9s ou les \u00ab&nbsp;formulaires de satisfaction&nbsp;\u00bb peuvent vous permettre de savoir ce que pensent vos collaborateurs de leur derni\u00e8re exp\u00e9rience de formation, vous aider \u00e0 voir comment ils ont utilis\u00e9 ce qu\u2019ils ont appris (de leur point de vue) et vous fournir des informations de qualit\u00e9 sur les moyens d\u2019am\u00e9liorer le L&D. Mais ces donn\u00e9es ne vont pas <em>au-del\u00e0<\/em> du L&D. Elles ne sont utiles \u00e0 personne d\u2019autre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces indicateurs de formation seront toujours essentiels pour faire du suivi. Mais comme les op\u00e9rations de RH et de L&D influencent de plus en plus les strat\u00e9gies d\u2019entreprise, les entreprises les plus avanc\u00e9es vont au-del\u00e0.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/1_6_21_New-Learning-Metrics_fr_FR_Blog-in-post-1-1024x460.png\" alt=\"\" class=\"wp-image-37703\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Demain&nbsp;: les indicateurs qui comptent pour l\u2019entreprise<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Votre entreprise a des besoins et des objectifs uniques&nbsp;: c\u2019est par l\u00e0 qu\u2019il faut commencer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Votre priorit\u00e9 est peut-\u00eatre de conserver votre \u00e9quipe de vente. Peut-\u00eatre voulez-vous <a href=\"https:\/\/get.degreed.com\/cognizant-case-study\" target=\"_blank\" rel=\"noreferrer noopener\">r\u00e9duire le temps n\u00e9cessaire aux ing\u00e9nieurs pour monter en comp\u00e9tences<\/a>, afin qu\u2019ils puissent rester en phase avec les \u00e9volutions technologiques. Ou encore, vous aimeriez que vos \u00e9quipes d\u2019assistance \u00e0 la client\u00e8le soient toujours inform\u00e9es des mises \u00e0 jour des produits. Ces \u00e9l\u00e9ments sont importants pour les managers de premier niveau et pour les dirigeants d\u2019entreprises, car ce sont eux qui influent sur leur capacit\u00e9 \u00e0 produire des r\u00e9sultats.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les nouveaux indicateurs de formation se veulent moins ax\u00e9s sur des consid\u00e9rations purement quantitatives. Ils ne privil\u00e9gient plus le temps pass\u00e9 \u00e0 se former, mettent davantage l\u2019accent sur les usages \u00e0 travers le prisme de la <strong>mobilisation<\/strong> des \u00e9quipes, et portent sur l\u2019apprentissage <strong>social <\/strong>et les <strong>contenus<\/strong>. Ils permettent de savoir de quelles <strong>comp\u00e9tences<\/strong> disposent vos collaborateurs et de quelles comp\u00e9tences ils ont besoin. Ils montrent \u00e9galement comment toutes ces donn\u00e9es peuvent avoir une influence sur les r\u00e9sultats qui int\u00e9ressent vos partenaires, et pas seulement vos \u00e9quipes responsables de la formation, des carri\u00e8res et des ressources humaines.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La collaboration de Degreed avec des centaines d\u2019entreprises parmi les plus innovantes du monde lui a permis de d\u00e9gager quatre&nbsp;nouvelles tendances qui, prises ensemble, dressent un tableau plus clair des \u00e9volutions des mentalit\u00e9s, des comportements et des comp\u00e9tences qui contribuent \u00e0 am\u00e9liorer les performances.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Votre r\u00e9cit sur l\u2019engagement<\/strong><strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous devez savoir si vos collaborateurs sont impliqu\u00e9s dans leur formation et s\u2019ils se sentent personnellement concern\u00e9s par le d\u00e9veloppement et l\u2019avancement de leur carri\u00e8re. Vous saurez ainsi si vous avez r\u00e9ussi \u00e0 instaurer une culture d\u2019innovation et d\u2019\u00e9volution propice \u00e0 g\u00e9n\u00e9rer des r\u00e9sultats tangibles. Votre r\u00e9cit sur l\u2019engagement porte sur&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Les activations<\/li><li>La fr\u00e9quence des connexions<\/li><li>Le nombre moyen d\u2019utilisateurs par mois et leur fid\u00e9lit\u00e9<\/li><li>Les t\u00e2ches effectu\u00e9es et termin\u00e9es<\/li><li>Le Net Promoter Score (NPS)<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Votre r\u00e9cit sur le partage entre pairs<\/strong><strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019objectif ici est de comprendre comment les collaborateurs \u00e0 tous les niveaux de votre organisation partagent leur savoir-faire, afin que la formation ne soit pas uniquement ax\u00e9e sur le L&D. Il s\u2019agit de d\u00e9couvrir comment ils interagissent pour s\u2019entraider par le biais d\u2019une formation collaborative entre pairs, bas\u00e9e sur le crowd-sourcing. Cela vous permet d\u2019identifier les personnes vers lesquelles les employ\u00e9s se tournent pour obtenir des conseils afin de rep\u00e9rer, d\u2019impliquer et de retenir les influenceurs et les experts. Votre r\u00e9cit sur le partage entre pairs se penche sur&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Les comp\u00e9tences tendances ou <a href=\"https:\/\/get.degreed.com\/fr\/state-of-skills-lp-france\" target=\"_blank\" rel=\"noreferrer noopener\">\u00e9mergentes<\/a><\/li><li>Les <a href=\"https:\/\/degreed.com\/experience\/fr\/blog\/degreed-does-data-how-learning-recommendations-work\/\" target=\"_blank\" rel=\"noreferrer noopener\">recommandations<\/a> de contenus, de personnes et d\u2019exp\u00e9riences<\/li><li>Les enseignements \u00e0 tirer, dont le pourcentage de collaborateurs qui les r\u00e9pertorient<\/li><li>Les influenceurs<ul><li>Les experts dans leur domaine<\/li><\/ul><ul><li>Les abonn\u00e9s<\/li><\/ul><ul><li>Les publications<\/li><\/ul><ul><li>L\u2019analyse du r\u00e9seau organisationnel <a href=\"https:\/\/www2.deloitte.com\/us\/en\/pages\/human-capital\/articles\/organizational-network-analysis.html\" target=\"_blank\" rel=\"noreferrer noopener\">(ONA)<\/a><\/li><\/ul><\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Votre r\u00e9cit sur les contenus<\/strong><strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vous devez savoir quelles comp\u00e9tences votre organisation est en train d\u2019acqu\u00e9rir. Vous pourrez ensuite vous demander ce que vos collaborateurs <em>veulent<\/em> apprendre, de quelle fa\u00e7on ils souhaitent se former et \u00e0 quel endroit. Votre r\u00e9cit sur les contenus porte sur&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Les recherches et les sujets les plus populaires<\/li><li>Les fournisseurs de contenu \u00e0 la demande<\/li><li>Le contenu consomm\u00e9 de mani\u00e8re <a href=\"https:\/\/get.degreed.com\/fr-fr\/how-the-workforce-learns-2021\" target=\"_blank\" rel=\"noreferrer noopener\">formelle et informelle<\/a>, en interne et en externe&nbsp;: cours, vid\u00e9os, podcasts, livres, etc.<\/li><li>Le contenu <a href=\"https:\/\/degreed.com\/experience\/blog\/how-the-workforce-learns-in-user-generated-content\/\" target=\"_blank\" rel=\"noreferrer noopener\">propos\u00e9 par les employ\u00e9s<\/a> (partage social)<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Votre r\u00e9cit sur les comp\u00e9tences<\/strong><strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il vous permet de savoir quels sont les atouts actuels de votre organisation et ceux qui lui font encore d\u00e9faut. Ces indicateurs r\u00e9pondent \u00e0 la question \u00ab&nbsp;Les programmes de formation sont-ils utiles&nbsp;?&nbsp;\u00bb. Votre r\u00e9cit sur les comp\u00e9tences aborde&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Les lacunes en mati\u00e8re de comp\u00e9tences<\/li><li>Les comp\u00e9tences \u00e9mergentes<\/li><li>La v\u00e9locit\u00e9 (vitesse \u00e0 laquelle se forment les employ\u00e9s)<\/li><li>L\u2019\u00e9volution des comp\u00e9tences (vitesse \u00e0 laquelle changent les profils de comp\u00e9tences individuels ou organisationnels)<\/li><li>La valeur des comp\u00e9tences (valeur mon\u00e9taire des comp\u00e9tences recherch\u00e9es)<\/li><li>La baisse du co\u00fbt des comp\u00e9tences (\u00e9conomies en mati\u00e8re de recrutement gr\u00e2ce \u00e0 la mont\u00e9e en comp\u00e9tence interne)<\/li><li>La pr\u00e9paration des \u00e9quipes<\/li><li>L\u2019identification des talents<\/li><li><a rel=\"noreferrer noopener\" href=\"https:\/\/degreed.com\/experience\/blog\/clearing-your-path-to-career-mobility\/\" target=\"_blank\">La mobilit\u00e9 interne<\/a><\/li><li>Les tendances<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/1_6_21_New-Learning-Metrics_fr_FR_Blog-in-post-2-1024x576.png\" alt=\"\" class=\"wp-image-37705\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Utilisation des indicateurs de formation pour rester agile<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Livrer votre r\u00e9cit d\u2019une nouvelle mani\u00e8re est un d\u00e9but. Il \u00e9voluera au fur et \u00e0 mesure que les donn\u00e9es seront collect\u00e9es. Les r\u00e9sultats obtenus apr\u00e8s 30&nbsp;jours seront diff\u00e9rents de ceux obtenus apr\u00e8s 60 ou 90&nbsp;jours, voire un&nbsp;an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est tout aussi important de d\u00e9velopper une culture et des processus qui utilisent les donn\u00e9es recueillies pour op\u00e9rer des changements qui permettent d\u2019am\u00e9liorer en permanence l\u2019alignement, l\u2019efficacit\u00e9 et l\u2019impact de vos investissements dans la formation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Votre r\u00e9cit sur les indicateurs de formation \u00e9voluera en fonction des besoins et des objectifs de votre entreprise. Chaque nouveau chapitre fournit des informations en temps r\u00e9el qui vous permettront de prendre de meilleures d\u00e9cisions.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour attirer l\u2019attention de votre direction et faire de votre programme de formation une priorit\u00e9 strat\u00e9gique, vous pouvez relater votre exp\u00e9rience en mati\u00e8re de perfectionnement des effectifs de mani\u00e8re originale, en vous appuyant sur de nouveaux indicateurs. M\u00eame si votre programme est d\u00e9j\u00e0 une priorit\u00e9, vous avez un r\u00e9cit \u00e0 livrer, qui permettra de renforcer [&hellip;]<\/p>\n","protected":false},"author":120,"featured_media":63823,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[],"tags":[],"post_folder":[],"class_list":["post-63820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les nouveaux indicateurs de la formation : d\u00e9montrer l\u2019impact et la valeur ajout\u00e9e pour l\u2019entreprise - Degreed<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les nouveaux indicateurs de la formation : d\u00e9montrer l\u2019impact et la valeur ajout\u00e9e pour l\u2019entreprise\" \/>\n<meta property=\"og:description\" content=\"Pour attirer l\u2019attention de votre direction et faire de votre programme de formation une priorit\u00e9 strat\u00e9gique, vous pouvez relater votre exp\u00e9rience en mati\u00e8re de perfectionnement des effectifs de mani\u00e8re originale, en vous appuyant sur de nouveaux indicateurs. M\u00eame si votre programme est d\u00e9j\u00e0 une priorit\u00e9, vous avez un r\u00e9cit \u00e0 livrer, qui permettra de renforcer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/\" \/>\n<meta property=\"og:site_name\" content=\"Degreed\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DegreedOfficial\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-06T16:12:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-29T06:41:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/1_6_21_New-Learning-Metrics_fr_FR_Blog-Header-1200x1200-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Susie Lee\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@degreed\" \/>\n<meta name=\"twitter:site\" content=\"@degreed\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Susie Lee\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/\"},\"author\":{\"name\":\"Susie Lee\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#\\\/schema\\\/person\\\/b3a491fae2121ea4f5773d2e0486cad2\"},\"headline\":\"Les nouveaux indicateurs de la formation : d\u00e9montrer l\u2019impact et la valeur ajout\u00e9e pour l\u2019entreprise\",\"datePublished\":\"2021-01-06T16:12:00+00:00\",\"dateModified\":\"2026-03-29T06:41:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/\"},\"wordCount\":1759,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1_6_21_New-Learning-Metrics_fr_FR_Blog-Header-1200x1200-1.png\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/\",\"url\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/\",\"name\":\"Les nouveaux indicateurs de la formation : d\u00e9montrer l\u2019impact et la valeur ajout\u00e9e pour l\u2019entreprise - Degreed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1_6_21_New-Learning-Metrics_fr_FR_Blog-Header-1200x1200-1.png\",\"datePublished\":\"2021-01-06T16:12:00+00:00\",\"dateModified\":\"2026-03-29T06:41:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1_6_21_New-Learning-Metrics_fr_FR_Blog-Header-1200x1200-1.png\",\"contentUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1_6_21_New-Learning-Metrics_fr_FR_Blog-Header-1200x1200-1.png\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les nouveaux indicateurs de la formation : d\u00e9montrer l\u2019impact et la valeur ajout\u00e9e pour l\u2019entreprise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/\",\"name\":\"Degreed\",\"description\":\"The Learning and Upskilling Platform\",\"publisher\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#organization\",\"name\":\"Degreed\",\"url\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo.svg\",\"caption\":\"Degreed\"},\"image\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DegreedOfficial\",\"https:\\\/\\\/x.com\\\/degreed\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/degreed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkH3pyPKVngvsZzZlmoH-Mw\",\"https:\\\/\\\/www.instagram.com\\\/degreed\\\/\"],\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"201\",\"maxValue\":\"500\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#\\\/schema\\\/person\\\/b3a491fae2121ea4f5773d2e0486cad2\",\"name\":\"Susie Lee\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/degreed-blog-1.png\",\"url\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/degreed-blog-1.png\",\"contentUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/degreed-blog-1.png\",\"caption\":\"Susie Lee\"},\"description\":\"Susie Lee is senior vice president and global business transformation officer at Degreed.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les nouveaux indicateurs de la formation : d\u00e9montrer l\u2019impact et la valeur ajout\u00e9e pour l\u2019entreprise - Degreed","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/","og_locale":"fr_FR","og_type":"article","og_title":"Les nouveaux indicateurs de la formation : d\u00e9montrer l\u2019impact et la valeur ajout\u00e9e pour l\u2019entreprise","og_description":"Pour attirer l\u2019attention de votre direction et faire de votre programme de formation une priorit\u00e9 strat\u00e9gique, vous pouvez relater votre exp\u00e9rience en mati\u00e8re de perfectionnement des effectifs de mani\u00e8re originale, en vous appuyant sur de nouveaux indicateurs. M\u00eame si votre programme est d\u00e9j\u00e0 une priorit\u00e9, vous avez un r\u00e9cit \u00e0 livrer, qui permettra de renforcer [&hellip;]","og_url":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/","og_site_name":"Degreed","article_publisher":"https:\/\/www.facebook.com\/DegreedOfficial","article_published_time":"2021-01-06T16:12:00+00:00","article_modified_time":"2026-03-29T06:41:47+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/1_6_21_New-Learning-Metrics_fr_FR_Blog-Header-1200x1200-1.png","type":"image\/png"}],"author":"Susie Lee","twitter_card":"summary_large_image","twitter_creator":"@degreed","twitter_site":"@degreed","twitter_misc":{"\u00c9crit par":"Susie Lee","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/#article","isPartOf":{"@id":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/"},"author":{"name":"Susie Lee","@id":"https:\/\/degreed.com\/experience\/fr\/#\/schema\/person\/b3a491fae2121ea4f5773d2e0486cad2"},"headline":"Les nouveaux indicateurs de la formation : d\u00e9montrer l\u2019impact et la valeur ajout\u00e9e pour l\u2019entreprise","datePublished":"2021-01-06T16:12:00+00:00","dateModified":"2026-03-29T06:41:47+00:00","mainEntityOfPage":{"@id":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/"},"wordCount":1759,"commentCount":0,"publisher":{"@id":"https:\/\/degreed.com\/experience\/fr\/#organization"},"image":{"@id":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/#primaryimage"},"thumbnailUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/1_6_21_New-Learning-Metrics_fr_FR_Blog-Header-1200x1200-1.png","inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/","url":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/","name":"Les nouveaux indicateurs de la formation : d\u00e9montrer l\u2019impact et la valeur ajout\u00e9e pour l\u2019entreprise - Degreed","isPartOf":{"@id":"https:\/\/degreed.com\/experience\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/#primaryimage"},"image":{"@id":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/#primaryimage"},"thumbnailUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/1_6_21_New-Learning-Metrics_fr_FR_Blog-Header-1200x1200-1.png","datePublished":"2021-01-06T16:12:00+00:00","dateModified":"2026-03-29T06:41:47+00:00","breadcrumb":{"@id":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/#primaryimage","url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/1_6_21_New-Learning-Metrics_fr_FR_Blog-Header-1200x1200-1.png","contentUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/1_6_21_New-Learning-Metrics_fr_FR_Blog-Header-1200x1200-1.png","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/degreed.com\/experience\/fr\/blog\/les-nouveaux-indicateurs-de-la-formation-demontrer-limpact-et-la-valeur-ajoutee-pour-lentreprise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/degreed.com\/experience\/fr\/"},{"@type":"ListItem","position":2,"name":"Les nouveaux indicateurs de la formation : d\u00e9montrer l\u2019impact et la valeur ajout\u00e9e pour l\u2019entreprise"}]},{"@type":"WebSite","@id":"https:\/\/degreed.com\/experience\/fr\/#website","url":"https:\/\/degreed.com\/experience\/fr\/","name":"Degreed","description":"The Learning and Upskilling Platform","publisher":{"@id":"https:\/\/degreed.com\/experience\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/degreed.com\/experience\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/degreed.com\/experience\/fr\/#organization","name":"Degreed","url":"https:\/\/degreed.com\/experience\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/degreed.com\/experience\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2023\/05\/logo.svg","contentUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2023\/05\/logo.svg","caption":"Degreed"},"image":{"@id":"https:\/\/degreed.com\/experience\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DegreedOfficial","https:\/\/x.com\/degreed","https:\/\/www.linkedin.com\/company\/degreed\/","https:\/\/www.youtube.com\/channel\/UCkH3pyPKVngvsZzZlmoH-Mw","https:\/\/www.instagram.com\/degreed\/"],"numberOfEmployees":{"@type":"QuantitativeValue","minValue":"201","maxValue":"500"}},{"@type":"Person","@id":"https:\/\/degreed.com\/experience\/fr\/#\/schema\/person\/b3a491fae2121ea4f5773d2e0486cad2","name":"Susie Lee","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/degreed-blog-1.png","url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/degreed-blog-1.png","contentUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/04\/degreed-blog-1.png","caption":"Susie Lee"},"description":"Susie Lee is senior vice president and global business transformation officer at Degreed."}]}},"_links":{"self":[{"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/posts\/63820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/users\/120"}],"replies":[{"embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/comments?post=63820"}],"version-history":[{"count":0,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/posts\/63820\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/media\/63823"}],"wp:attachment":[{"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/media?parent=63820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/categories?post=63820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/tags?post=63820"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/post_folder?post=63820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}