{"id":88329,"date":"2026-02-19T22:06:08","date_gmt":"2026-02-19T22:06:08","guid":{"rendered":"https:\/\/degreed.com\/experience\/?p=88329"},"modified":"2026-03-06T19:01:37","modified_gmt":"2026-03-06T19:01:37","slug":"comment-ia-redessine-avenir-technologies-formation","status":"publish","type":"post","link":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/","title":{"rendered":"Comment l\u2019IA redessine l\u2019avenir des technologies de formation"},"content":{"rendered":"\n<p>Les technologies de formation n\u2019ont pas \u00e9t\u00e9 con\u00e7ues pour le monde actuel.<\/p>\n\n<p>La plupart des plateformes ont \u00e9t\u00e9 pens\u00e9es pour des postes stables, des comp\u00e9tences pr\u00e9visibles et des \u00e9volutions lin\u00e9aires.  Or, aujourd\u2019hui, les strat\u00e9gies peuvent changer en cours d\u2019ann\u00e9e et les outils d\u2019IA \u00e9voluent chaque mois. Les attentes changent plus vite que les \u00e9quipes n\u2019ont le temps d\u2019int\u00e9grer ce qu\u2019on leur demandait hier.<\/p>\n\n<p>Dans un tel contexte, le learning ne peut plus se limiter \u00e0 une simple diffusion d\u2019informations. La formation doit permettre \u00e0 chacun de s\u2019adapter rapidement, r\u00e9guli\u00e8rement et en temps r\u00e9el.\u00a0<\/p>\n\n<p>Cette dynamique de changement permanent s\u2019est intensifi\u00e9e sous l\u2019effet de l\u2019accessibilit\u00e9 croissante et de l\u2019innovation des outils d\u2019IA, qui transforment notre mani\u00e8re de travailler. Mais le vrai sujet n\u2019est pas l\u2019IA. C\u2019est le changement. C\u2019est lui qui pousse les outils de formation \u00e0 d\u00e9passer le contenu pour devenir plus concrets, plus immersifs et plus proches de la r\u00e9alit\u00e9 du terrain.<\/p>\n\n<p>Lors d\u2019un webinaire Degreed consacr\u00e9 \u00e0 l\u2019avenir des outils de formation \u00e0 l\u2019\u00e8re de l\u2019IA (<a href=\"https:\/\/get.degreed.com\/ai-learning-revolution\" target=\"_blank\" rel=\"noreferrer noopener\">The AI-Powered Future of Learning Technology<\/a> \u2013 en anglais), des responsables de Boehringer Ingelheim et de Fosway Group ont justement fait le point sur ces technologies \u00e0 l&rsquo;heure o\u00f9 l\u2019IA passe d&rsquo;une phase exp\u00e9rimentale \u00e0 une phase op\u00e9rationnelle.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-1-ai-can-finally-bridge-the-gap-between-business-strategy-and-l-amp-d\">1. L\u2019IA permet enfin de relier strat\u00e9gie d\u2019entreprise et fonction L&D<\/h3>\n\n<p>Les leaders ont une id\u00e9e claire des objectifs \u00e0 atteindre. Ce qui fait souvent d\u00e9faut, c\u2019est une vision claire et partag\u00e9e des comp\u00e9tences \u00e0 faire \u00e9voluer pour atteindre ces objectifs.<\/p>\n\n<p>Martin Hess, directeur de la formation chez Boehringer Ingelheim, sugg\u00e8re une approche simple mais efficace\u00a0: utiliser l\u2019IA pour analyser les documents strat\u00e9giques de l\u2019entreprise et produire une premi\u00e8re cartographie des comp\u00e9tences requises.\u00a0<\/p>\n\n<p>Au lieu de discussions abstraites sur la transformation, les responsables formation peuvent arriver avec des \u00e9l\u00e9ments concrets\u00a0: \u00ab\u00a0Sur la base de votre strat\u00e9gie, voici les dix comp\u00e9tences qui semblent les plus critiques. Voyons si cela tient la route.\u00a0\u00bb<\/p>\n\n<p>R\u00e9sultat\u00a0: une meilleure coordination, des dirigeants plus investis et un learning adaptatif guid\u00e9 par les priorit\u00e9s r\u00e9elles de l\u2019entreprise plut\u00f4t que par des r\u00e9f\u00e9rentiels g\u00e9n\u00e9riques. L\u2019IA n\u2019a pas vocation \u00e0 remplacer l\u2019intelligence humaine ici. Elle r\u00e9duit les frictions et aligne plus rapidement les \u00e9quipes.<\/p>\n\n<h3 class=\"wp-block-heading\" id=\"h-2-virtual-reality-vr-and-ai-tools-are-making-realistic-practice-possible-and-scalable\">2. La r\u00e9alit\u00e9 virtuelle (RV) et l\u2019IA transforment la formation en une pratique immersive accessible \u00e0 grande \u00e9chelle<\/h3>\n\n<p>Depuis des d\u00e9cennies, les \u00e9quipes L&D insistent sur l\u2019importance de la pratique pour consolider les acquis, notamment les \u00ab\u00a0soft skills\u00a0\u00bb ou comp\u00e9tences intangibles mobilis\u00e9es dans les interactions commerciales, les situations de leadership et les conversations d\u00e9licates.\u00a0\u00a0<\/p>\n\n<p>Dans les faits, peu de collaborateurs ont la possibilit\u00e9 de s\u2019entra\u00eener de mani\u00e8re contr\u00f4l\u00e9e et r\u00e9p\u00e9t\u00e9e avant que l\u2019enjeu ne devienne r\u00e9el. Le coaching individuel est efficace, mais co\u00fbteux. Les mises en situation fonctionnent, mais seulement en petits groupes. En fin de compte, beaucoup n\u2019ont tout simplement pas suffisamment de pratique pour d\u00e9velopper l\u2019assurance dont ils ont besoin.<\/p>\n\n<p>L\u2019IA et la RV ouvrent aujourd\u2019hui un nouveau champ des possibles. Les simulations pilot\u00e9es par l\u2019IA et les environnements immersifs permettent d\u00e9sormais de s\u2019entra\u00eener sur des sc\u00e9narios concrets, comme un pitch commercial, une n\u00e9gociation strat\u00e9gique ou un entretien d\u2019\u00e9valuation. Pas en regardant une vid\u00e9o ou en lisant un article, mais en participant activement, en r\u00e9pondant, en ajustant et en r\u00e9essayant, avec \u00e0 la cl\u00e9 des \u00e9quipes op\u00e9rationnelles bien plus rapidement.\u00a0<\/p>\n\n<p>\u00ab\u00a0\u00c0 mon sens, aucune entreprise sur cette plan\u00e8te ne peut se permettre d\u2019offrir un coach personnel \u00e0 chaque collaborateur\u00a0\u00bb, d\u00e9clare Martin Hess. \u00ab\u00a0Maintenant, cela devient enfin accessible et r\u00e9alisable. Nous pouvons proposer une exp\u00e9rience ultra-personnalis\u00e9e \u00e0 presque tous, \u00e0 grande \u00e9chelle. C\u2019est une v\u00e9ritable r\u00e9volution.\u00a0\u00bb<\/p>\n\n<p>Ce changement entra\u00eene deux \u00e9volutions majeures\u00a0:<\/p>\n\n<ol class=\"wp-block-list\">\n<li><strong>La pratique devient g\u00e9n\u00e9ralisable. <\/strong>Ce qui n\u00e9cessitait autrefois un coaching individuel co\u00fbteux ou des mises en situation en petits groupes peut d\u00e9sormais \u00eatre propos\u00e9 \u00e0 plus de collaborateurs, sans perte d\u2019impact.<\/li>\n\n\n\n<li><strong>Le cadre devient plus s\u00e9curisant.<\/strong> Les collaborateurs peuvent exp\u00e9rimenter, se tromper et <a href=\"https:\/\/trainingindustry.com\/articles\/learning-technologies\/the-holistic-roi-of-immersive-learning-technologies-a-business-case-for-xr-and-vr\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">gagner en assurance<\/a> lorsqu\u2019ils s\u2019entra\u00eenent, sans craindre d\u2019\u00eatre \u00e9valu\u00e9s par un autre humain. La pression redescend.\u00a0<\/li>\n<\/ol>\n\n<p>Tous les collaborateurs peuvent d\u00e9sormais s\u2019entra\u00eener r\u00e9guli\u00e8rement \u00e0 des situations critiques pour l\u2019entreprise, dans leur contexte r\u00e9el et sans crainte de jugement.<\/p>\n\n<p>La pratique ne constitue plus un privil\u00e8ge r\u00e9serv\u00e9 \u00e0 quelques-uns et devient un \u00e9l\u00e9ment cl\u00e9 du d\u00e9veloppement des comp\u00e9tences au sein de l\u2019organisation. Ces outils offrent \u00e0 davantage de collaborateurs un environnement s\u00e9curis\u00e9 pour prendre confiance en amont, afin d\u2019aborder les conversations cl\u00e9s avec plus de s\u00e9r\u00e9nit\u00e9.<\/p>\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/degreed.com\/experience\/fr\/artificial-intelligence\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/02\/Maestro_Blog-CTA_fr_FR-1024x213.png\" alt=\"\" class=\"wp-image-87864\" \/><\/a><\/figure>\n\n<h3 class=\"wp-block-heading\">3. L\u2019avenir du L&D repose sur la mont\u00e9e en comp\u00e9tences des \u00e9quipes dans cet environnement technologique en constante \u00e9volution<\/h3>\n\n<p>Au lieu de s\u2019appuyer sur des processus h\u00e9rit\u00e9s et manuels, les organisations peuvent red\u00e9ployer leurs talents et s\u2019orienter davantage vers des workflows pilot\u00e9s par l\u2019IA. Cela vaut pour la formation et le d\u00e9veloppement autant que pour les autres fonctions de l\u2019entreprise. Autrement dit, les \u00e9quipes formation doivent \u00eatre aussi \u00e0 l\u2019aise avec l\u2019IA que les collaborateurs qu\u2019elles accompagnent.<\/p>\n\n<p>Chez Boehringer Ingelheim, le virage a \u00e9t\u00e9 pris tout de suite. La fonction formation s\u2019est mobilis\u00e9e \u00e0 100\u00a0% d\u00e8s le d\u00e9part, en d\u00e9veloppant les comp\u00e9tences non seulement des \u00e9quipes L&D, mais aussi des responsables RH et des dirigeants. L\u2019objectif n\u2019\u00e9tait pas de les transformer en experts techniques, mais de leur permettre de comprendre ce que l\u2019IA peut faire, comment elle fonctionne et quels risques elle comporte.<\/p>\n\n<p>La fonction L&D se trouve aujourd\u2019hui \u00e0 la crois\u00e9e des chemins. L\u2019adoption de l\u2019IA peut soit r\u00e9duire son r\u00f4le, soit le renforcer\u00a0: tout d\u00e9pendra de la capacit\u00e9 des \u00e9quipes \u00e0 s\u2019emparer des possibilit\u00e9s qu\u2019offre ce nouveau mod\u00e8le op\u00e9rationnel.<\/p>\n\n<p>Fiona Leteney encourage les professionnels du learning \u00e0 rapidement se former sur l\u2019IA pour prendre la t\u00eate du mouvement et contribuer au choix des outils\u00a0: \u00ab\u00a0Il faut acc\u00e9l\u00e9rer maintenant si ce n\u2019est pas d\u00e9j\u00e0 fait, car le reste de l\u2019entreprise avance et les d\u00e9cisions pourraient vous \u00eatre impos\u00e9es.\u00a0\u00bb<\/p>\n\n<p>La question ne se limite pas au choix des outils. Il s\u2019agit de red\u00e9finir en profondeur le r\u00f4le du L&D \u00e0 l\u2019\u00e8re de l\u2019IA. Dans ce contexte, de nombreux professionnels s\u2019int\u00e9ressent \u00e0 la cr\u00e9ation de contenus.\u00a0<\/p>\n\n<h3 class=\"wp-block-heading\">4. La cr\u00e9ation de contenus assist\u00e9e par l\u2019IA devient une priorit\u00e9 pour le L&D<\/h3>\n\n<p>Parmi les usages de l\u2019IA dans les outils de learning, cr\u00e9er des contenus arrive facilement en t\u00eate. Selon une \u00e9tude de Fosway Group cit\u00e9e par Fiona Leteney, 71\u00a0% des r\u00e9pondants d\u00e9clarent qu\u2019ils pr\u00e9voient d\u2019utiliser l\u2019IA pour soutenir la cr\u00e9ation de contenus.<\/p>\n\n<p>Ce processus peut prendre des formes diff\u00e9rentes selon les besoins. Les nouvelles capacit\u00e9s IA peuvent notamment\u00a0:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>convertir des supports denses en formats plus interactifs et multimodaux,<\/li>\n\n\n\n<li>mettre \u00e0 jour rapidement les contenus \u00e0 mesure que les politiques, outils et priorit\u00e9s \u00e9voluent,<\/li>\n\n\n\n<li>simplifier des informations complexes pour les rendre plus claires et plus faciles \u00e0 assimiler.<\/li>\n<\/ul>\n\n<p>Il faut toutefois rappeler qu\u2019il s\u2019agit uniquement d\u2019un soutien. L\u2019intervention humaine reste indispensable pour assurer la qualit\u00e9 et la pertinence des contenus. Cela signifie que certains sp\u00e9cialistes learning pourront consacrer davantage de temps \u00e0 des t\u00e2ches \u00e0 valeur ajout\u00e9e plut\u00f4t qu\u2019\u00e0 des op\u00e9rations r\u00e9p\u00e9titives et manuelles.<\/p>\n\n<h3 class=\"wp-block-heading\">5. Une gouvernance et une conformit\u00e9 ma\u00eetris\u00e9es simplifieront le d\u00e9ploiement des outils de learning<\/h3>\n\n<p>Les technologies propuls\u00e9es par l\u2019IA ont ouvert la voie \u00e0 de nouvelles exigences et pratiques en mati\u00e8re de s\u00e9curit\u00e9, qui doivent \u00eatre prises en compte dans tout projet d\u2019impl\u00e9mentation technologique. Chaque ann\u00e9e voit \u00e9merger de nouvelles directives sur l\u2019IA. L\u2019Union europ\u00e9enne a \u00e9t\u00e9 la <a href=\"https:\/\/www.europarl.europa.eu\/topics\/en\/article\/20230601STO93804\/eu-ai-act-first-regulation-on-artificial-intelligence\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">premi\u00e8re \u00e0 adopter un cadre l\u00e9gislatif complet sur l\u2019IA<\/a>, et rien qu\u2019aux \u00c9tats-Unis, des <a href=\"https:\/\/www.ncsl.org\/technology-and-communication\/artificial-intelligence-2025-legislation\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">centaines de r\u00e9glementations li\u00e9es \u00e0 l\u2019IA ont vu le jour en 2025<\/a>.\u00a0<\/p>\n\n<p>Face \u00e0 des technologies IA en constante mutation, les \u00e9quipes juridiques sont sous pression. Elles d\u00e9couvrent de nombreux outils et technologies de formation IA pour la premi\u00e8re fois, tout en devant garantir la s\u00e9curit\u00e9 et la conformit\u00e9 de l\u2019entreprise. Mais les choses avancent. Plus les \u00e9quipes juridiques travaillent avec l\u2019IA et s\u2019approprient ces outils, plus les d\u00e9cisions en mati\u00e8re de gouvernance sont prises rapidement.<\/p>\n\n<p>\u00c0 l\u2019\u00e8re des nouvelles technologies de formation, les \u00e9quipes juridiques et de gouvernance ne doivent plus \u00eatre per\u00e7ues comme un frein, mais comme de v\u00e9ritables partenaires. Int\u00e9grez-les d\u00e8s le d\u00e9part. Donnez-leur l\u2019espace pour apprendre aux c\u00f4t\u00e9s des \u00e9quipes L&D, mais aussi apporter leur contribution sur la s\u00e9curit\u00e9 et les dispositifs de contr\u00f4le et contribuer \u00e0 r\u00e9duire les obstacles en aval.\u00a0<\/p>\n\n<p>Martin Hess le dit tr\u00e8s bien\u00a0: \u00ab Int\u00e9grez les \u00e9quipes juridiques. Associez aussi les repr\u00e9sentants du personnel. Faites-les avancer \u00e0 vos c\u00f4t\u00e9s, car eux aussi d\u00e9butent avec l\u2019IA. Gardez-le \u00e0 l\u2019esprit, et faites preuve de bienveillance. C\u2019est tr\u00e8s, tr\u00e8s important.\u00a0\u00bb<\/p>\n\n<h3 class=\"wp-block-heading\">Vers des technologies de formation plus matures et ma\u00eetris\u00e9es<\/h3>\n\n<p>Les technologies de formation ne seront jamais fig\u00e9es. Elles doivent continuer \u00e0 \u00e9voluer au rythme des besoins de l\u2019organisation et des capacit\u00e9s des \u00e9quipes. Mais une chose est s\u00fbre\u00a0: les \u00e9quipes learning et les outils qu\u2019elles mobilisent doivent aider l\u2019entreprise \u00e0 traduire en permanence l\u2019\u00e9volution des priorit\u00e9s en comp\u00e9tences concr\u00e8tes. Elles doivent ouvrir des espaces pour la mise en pratique, renforcer les comp\u00e9tences sans augmenter les effectifs, et \u00e9voluer de mani\u00e8re responsable dans le respect des exigences de gouvernance, de r\u00e9glementation et de confiance.<\/p>\n\n<p>Une telle transformation ne se fait pas de mani\u00e8re isol\u00e9e. Elle repose sur une collaboration \u00e9troite entre dirigeants, \u00e9diteurs de solutions et \u00e9quipes learning, RH et IT. Comme le souligne Fiona Leteney\u00a0: \u00ab\u00a0Ce sont les \u00e9changes entre fournisseurs et entreprises qui feront la diff\u00e9rence, car c\u2019est ensemble que l\u2019avenir se construit.\u00a0\u00bb<\/p>\n\n<p>Pour les organisations et les \u00e9quipes L&D pr\u00eates \u00e0 se former rapidement, \u00e0 adopter l\u2019IA et \u00e0 embarquer leurs \u00e9quipes, l\u2019avenir des technologies de formation est d\u00e9j\u00e0 l\u00e0.<\/p>\n\n<p>\u2192 <a href=\"https:\/\/get.degreed.com\/ai-learning-revolution\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Regardez l\u2019int\u00e9gralit\u00e9 du webinaire <em>L\u2019avenir des technologies learning pilot\u00e9es par l\u2019IA<\/em><\/strong> <strong>et deux autres sessions de notre s\u00e9rie La r\u00e9volution de l\u2019IA.<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les technologies de formation n\u2019ont pas \u00e9t\u00e9 con\u00e7ues pour le monde actuel. La plupart des plateformes ont \u00e9t\u00e9 pens\u00e9es pour des postes stables, des comp\u00e9tences pr\u00e9visibles et des \u00e9volutions lin\u00e9aires. Or, aujourd\u2019hui, les strat\u00e9gies peuvent changer en cours d\u2019ann\u00e9e et les outils d\u2019IA \u00e9voluent chaque mois. Les attentes changent plus vite que les \u00e9quipes n\u2019ont [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":88267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[641],"tags":[],"post_folder":[],"class_list":["post-88329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ai-innovation-in-learning"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comment l\u2019IA redessine l\u2019avenir des technologies de formation - Degreed<\/title>\n<meta name=\"description\" content=\"Les technologies learning \u00e9voluent. D\u00e9couvrez comment l\u2019IA et la VR d\u00e9veloppent la pratique, comblent l\u2019\u00e9cart strat\u00e9gie-comp\u00e9tences et red\u00e9finissent le L&amp;D.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment l\u2019IA redessine l\u2019avenir des technologies de formation\" \/>\n<meta property=\"og:description\" content=\"Les technologies learning \u00e9voluent. D\u00e9couvrez comment l\u2019IA et la VR d\u00e9veloppent la pratique, comblent l\u2019\u00e9cart strat\u00e9gie-comp\u00e9tences et red\u00e9finissent le L&amp;D.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/\" \/>\n<meta property=\"og:site_name\" content=\"Degreed\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DegreedOfficial\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-19T22:06:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-06T19:01:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/02\/future-learning-technology.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emily Gerson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@degreed\" \/>\n<meta name=\"twitter:site\" content=\"@degreed\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emily Gerson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/comment-ia-redessine-avenir-technologies-formation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/comment-ia-redessine-avenir-technologies-formation\\\/\"},\"author\":{\"name\":\"Emily Gerson\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#\\\/schema\\\/person\\\/75f8eb36198972efce535ddbf2c12e13\"},\"headline\":\"Comment l\u2019IA redessine l\u2019avenir des technologies de formation\",\"datePublished\":\"2026-02-19T22:06:08+00:00\",\"dateModified\":\"2026-03-06T19:01:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/comment-ia-redessine-avenir-technologies-formation\\\/\"},\"wordCount\":1871,\"publisher\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/comment-ia-redessine-avenir-technologies-formation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/future-learning-technology.png\",\"articleSection\":[\"IA et innovations learning\u00a0\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/comment-ia-redessine-avenir-technologies-formation\\\/\",\"url\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/comment-ia-redessine-avenir-technologies-formation\\\/\",\"name\":\"Comment l\u2019IA redessine l\u2019avenir des technologies de formation - Degreed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/comment-ia-redessine-avenir-technologies-formation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/comment-ia-redessine-avenir-technologies-formation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/future-learning-technology.png\",\"datePublished\":\"2026-02-19T22:06:08+00:00\",\"dateModified\":\"2026-03-06T19:01:37+00:00\",\"description\":\"Les technologies learning \u00e9voluent. D\u00e9couvrez comment l\u2019IA et la VR d\u00e9veloppent la pratique, comblent l\u2019\u00e9cart strat\u00e9gie-comp\u00e9tences et red\u00e9finissent le L&D.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/comment-ia-redessine-avenir-technologies-formation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/comment-ia-redessine-avenir-technologies-formation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/comment-ia-redessine-avenir-technologies-formation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/future-learning-technology.png\",\"contentUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/future-learning-technology.png\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/blog\\\/comment-ia-redessine-avenir-technologies-formation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment l\u2019IA redessine l\u2019avenir des technologies de formation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/\",\"name\":\"Degreed\",\"description\":\"The Learning and Upskilling Platform\",\"publisher\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#organization\",\"name\":\"Degreed\",\"url\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo.svg\",\"caption\":\"Degreed\"},\"image\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DegreedOfficial\",\"https:\\\/\\\/x.com\\\/degreed\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/degreed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkH3pyPKVngvsZzZlmoH-Mw\",\"https:\\\/\\\/www.instagram.com\\\/degreed\\\/\"],\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"201\",\"maxValue\":\"500\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/fr\\\/#\\\/schema\\\/person\\\/75f8eb36198972efce535ddbf2c12e13\",\"name\":\"Emily Gerson\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-emily-gerson-96x96.jpg\",\"url\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-emily-gerson-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-emily-gerson-96x96.jpg\",\"caption\":\"Emily Gerson\"},\"description\":\"Emily Gerson is a copywriter at Degreed.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comment l\u2019IA redessine l\u2019avenir des technologies de formation - Degreed","description":"Les technologies learning \u00e9voluent. D\u00e9couvrez comment l\u2019IA et la VR d\u00e9veloppent la pratique, comblent l\u2019\u00e9cart strat\u00e9gie-comp\u00e9tences et red\u00e9finissent le L&D.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment l\u2019IA redessine l\u2019avenir des technologies de formation","og_description":"Les technologies learning \u00e9voluent. D\u00e9couvrez comment l\u2019IA et la VR d\u00e9veloppent la pratique, comblent l\u2019\u00e9cart strat\u00e9gie-comp\u00e9tences et red\u00e9finissent le L&D.","og_url":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/","og_site_name":"Degreed","article_publisher":"https:\/\/www.facebook.com\/DegreedOfficial","article_published_time":"2026-02-19T22:06:08+00:00","article_modified_time":"2026-03-06T19:01:37+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/02\/future-learning-technology.png","type":"image\/png"}],"author":"Emily Gerson","twitter_card":"summary_large_image","twitter_creator":"@degreed","twitter_site":"@degreed","twitter_misc":{"\u00c9crit par":"Emily Gerson","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/#article","isPartOf":{"@id":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/"},"author":{"name":"Emily Gerson","@id":"https:\/\/degreed.com\/experience\/fr\/#\/schema\/person\/75f8eb36198972efce535ddbf2c12e13"},"headline":"Comment l\u2019IA redessine l\u2019avenir des technologies de formation","datePublished":"2026-02-19T22:06:08+00:00","dateModified":"2026-03-06T19:01:37+00:00","mainEntityOfPage":{"@id":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/"},"wordCount":1871,"publisher":{"@id":"https:\/\/degreed.com\/experience\/fr\/#organization"},"image":{"@id":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/#primaryimage"},"thumbnailUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/02\/future-learning-technology.png","articleSection":["IA et innovations learning\u00a0"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/","url":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/","name":"Comment l\u2019IA redessine l\u2019avenir des technologies de formation - Degreed","isPartOf":{"@id":"https:\/\/degreed.com\/experience\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/#primaryimage"},"image":{"@id":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/#primaryimage"},"thumbnailUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/02\/future-learning-technology.png","datePublished":"2026-02-19T22:06:08+00:00","dateModified":"2026-03-06T19:01:37+00:00","description":"Les technologies learning \u00e9voluent. D\u00e9couvrez comment l\u2019IA et la VR d\u00e9veloppent la pratique, comblent l\u2019\u00e9cart strat\u00e9gie-comp\u00e9tences et red\u00e9finissent le L&D.","breadcrumb":{"@id":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/#primaryimage","url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/02\/future-learning-technology.png","contentUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2026\/02\/future-learning-technology.png","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/degreed.com\/experience\/fr\/blog\/comment-ia-redessine-avenir-technologies-formation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/degreed.com\/experience\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment l\u2019IA redessine l\u2019avenir des technologies de formation"}]},{"@type":"WebSite","@id":"https:\/\/degreed.com\/experience\/fr\/#website","url":"https:\/\/degreed.com\/experience\/fr\/","name":"Degreed","description":"The Learning and Upskilling Platform","publisher":{"@id":"https:\/\/degreed.com\/experience\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/degreed.com\/experience\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/degreed.com\/experience\/fr\/#organization","name":"Degreed","url":"https:\/\/degreed.com\/experience\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/degreed.com\/experience\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2023\/05\/logo.svg","contentUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2023\/05\/logo.svg","caption":"Degreed"},"image":{"@id":"https:\/\/degreed.com\/experience\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DegreedOfficial","https:\/\/x.com\/degreed","https:\/\/www.linkedin.com\/company\/degreed\/","https:\/\/www.youtube.com\/channel\/UCkH3pyPKVngvsZzZlmoH-Mw","https:\/\/www.instagram.com\/degreed\/"],"numberOfEmployees":{"@type":"QuantitativeValue","minValue":"201","maxValue":"500"}},{"@type":"Person","@id":"https:\/\/degreed.com\/experience\/fr\/#\/schema\/person\/75f8eb36198972efce535ddbf2c12e13","name":"Emily Gerson","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/cropped-emily-gerson-96x96.jpg","url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/cropped-emily-gerson-96x96.jpg","contentUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/cropped-emily-gerson-96x96.jpg","caption":"Emily Gerson"},"description":"Emily Gerson is a copywriter at Degreed."}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/posts\/88329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/comments?post=88329"}],"version-history":[{"count":0,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/posts\/88329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/media\/88267"}],"wp:attachment":[{"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/media?parent=88329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/categories?post=88329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/tags?post=88329"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/fr\/wp-json\/wp\/v2\/post_folder?post=88329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}