{"id":86148,"date":"2025-05-29T16:37:03","date_gmt":"2025-05-29T16:37:03","guid":{"rendered":"https:\/\/degreed.com\/experience\/?p=86148"},"modified":"2025-12-16T21:06:43","modified_gmt":"2025-12-16T21:06:43","slug":"how-the-workforce-learns-gen-ai-see-what-2700-leaders-say","status":"publish","type":"post","link":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/","title":{"rendered":"Como a for\u00e7a de trabalho aprende GenIA: o que 2.700 l\u00edderes t\u00eam a dizer"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Com tantas transforma\u00e7\u00f5es que a intelig\u00eancia artificial vem provocando na forma como trabalhamos, precisamos urgentemente adaptar nossas estrat\u00e9gias de aprendizagem.<\/p>\n\n<p class=\"wp-block-paragraph\">Contudo, o <a href=\"https:\/\/get.degreed.com\/how-the-workforce-learns-2025-pre-release\" target=\"_blank\" rel=\"noreferrer noopener\">relat\u00f3rio da Degreed <em>Como a for\u00e7a de trabalho aprende GenIA em 2025<\/em><\/a><em> <\/em>exp\u00f5e uma dura realidade: <strong>68% dos profissionais afirmam que suas organiza\u00e7\u00f5es oferecem pouco ou nenhum apoio estruturado para que aprendam IA generativa<\/strong>, for\u00e7ando-os a \u201cirem \u00e0 luta por conta pr\u00f3pria\u201d e colocando em risco a ado\u00e7\u00e3o da tecnologia em larga escala.<\/p>\n\n<p class=\"wp-block-paragraph\">Com isso, <strong>66% dos colaboradores ainda est\u00e3o nos n\u00edveis mais b\u00e1sicos do dom\u00ednio da IA<\/strong>. Para CLOs, l\u00edderes de gest\u00e3o de talentos e estrategistas de RH, essa lacuna \u00e9 uma oportunidade estrat\u00e9gica para reimaginar a aprendizagem corporativa como um instrumento de vantagem competitiva.<\/p>\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/get.degreed.com\/pt-br\/how-the-workforce-learns\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/07\/HWL-Blog-CTA_pt_BR_HWL-Blog-CTA-1024x200.png\" alt=\"\" class=\"wp-image-85062\" \/><\/a><\/figure>\n\n<h2 class=\"wp-block-heading\">A mudan\u00e7a por conta pr\u00f3pria<\/h2>\n\n<p class=\"wp-block-paragraph\">Em parceria com a <a href=\"https:\/\/hbr.org\/about-hbp\" target=\"_blank\" rel=\"noreferrer noopener\">Harvard Business Publishing<\/a>, promovemos uma pesquisa com mais de 2.700 l\u00edderes de alto e m\u00e9dio escal\u00e3o em empresas de diversos setores e atuantes em diversas partes do mundo. T\u00ednhamos um \u00fanico objetivo: descobrir como os colaboradores est\u00e3o desenvolvendo suas habilidades de IA \u2014 e o que as organiza\u00e7\u00f5es podem fazer para criar uma for\u00e7a de trabalho fluente nessa tecnologia, a fim de aproveitar todo o potencial que a IA generativa oferece.<\/p>\n\n<p class=\"wp-block-paragraph\">\u201cA IA tem impacto sobre toda a organiza\u00e7\u00e3o\u201d, pontua Lisa Tenorio, vice-presidente s\u00eanior de produto e inova\u00e7\u00e3o da Harvard Business Publishing, que <a href=\"https:\/\/events.degreed.com\/LENS2025\" target=\"_blank\" rel=\"noreferrer noopener\">apresentou uma pr\u00e9via da pesquisa no Degreed LENS 2025<\/a>. \u201cN\u00e3o se trata de uma \u00fanica \u00e1rea funcional. Todo mundo, em todos os n\u00edveis da empresa, precisa ter alguma flu\u00eancia em IA, al\u00e9m de precisar manter a continuidade da aprendizagem para acompanhar a r\u00e1pida evolu\u00e7\u00e3o da tecnologia. Por isso, tanto os aprendizes quanto os programas de aprendizagem precisam se adaptar e continuar evoluindo\u201d, recomenda Tenorio.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/06\/05-08-Why-Everyones-Talking-About-These-8-Degreed-Partners_Localization_pt_BR_CTA-1280x250-1-1024x201.png\" alt=\"\" class=\"wp-image-84477\" \/><\/figure>\n\n<p class=\"wp-block-paragraph\">Encontramos colaboradores que n\u00e3o est\u00e3o esperando permiss\u00e3o para come\u00e7ar essa jornada. Muitos j\u00e1 est\u00e3o separando um tempo em suas agendas para se aprofundarem ativamente em IA e outras ferramentas que v\u00eam despontando no mercado. Por meio de experimentos pr\u00e1ticos, a for\u00e7a de trabalho atual est\u00e1 sinalizando que h\u00e1 uma grande demanda para a aprendizagem \u00e1gil e personalizada.<\/p>\n\n<p class=\"wp-block-paragraph\">No entanto, n\u00e3o basta ter automotiva\u00e7\u00e3o. Sem clareza nas orienta\u00e7\u00f5es e na estrutura, os riscos de desinforma\u00e7\u00e3o, desperd\u00edcio de tempo e falta de engajamento s\u00f3 crescem. E os n\u00fameros mostram exatamente isso: segundo o relat\u00f3rio, <strong>40% dos colaboradores que est\u00e3o explorando a IA por conta pr\u00f3pria relatam a sensa\u00e7\u00e3o de sobrecarga ou de incerteza sobre como aplic\u00e1-la.<\/strong><\/p>\n\n<h2 class=\"wp-block-heading\">Facilitadores da flu\u00eancia em IA<\/h2>\n\n<p class=\"wp-block-paragraph\">Para viabilizar uma transforma\u00e7\u00e3o expressiva, organiza\u00e7\u00f5es vision\u00e1rias priorizam fatores-chave, tais como:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Apoio da lideran\u00e7a:<\/strong> transforma\u00e7\u00e3o nenhuma acontece sem o apoio da equipe executiva. As iniciativas de aprendizagem prosperam quando a lideran\u00e7a demonstra apoio e participa ativamente delas \u2014 sim, com a\u00e7\u00f5es, n\u00e3o apenas da boca para fora. \u00c9 fundamental alocar tempo e verba para a aprendizagem, vincular diretamente a aprendizagem a objetivos da empresa e ser um exemplo a ser seguido em termos de h\u00e1bitos de estudo. Mesmo assim, os participantes da pesquisa indicaram que <strong>apenas 13% das organiza\u00e7\u00f5es apoiam, ao mesmo tempo, todos os tr\u00eas facilitadores de flu\u00eancia em IA<\/strong>, ou seja, lideran\u00e7a, ferramentas e ambiente.<br \/><\/li>\n\n\n\n<li><strong>Ferramentas e tecnologia:<\/strong> as plataformas modernas devem ir al\u00e9m da distribui\u00e7\u00e3o de conte\u00fados. Elas precisam facilitar a descoberta de conte\u00fados, personaliz\u00e1-los e torn\u00e1-los mais pr\u00e1ticos. Ou seja, \u00e9 importante <a href=\"https:\/\/degreed.com\/experience\/blog\/degreed-automations-easily-personalize-learning-from-day-1\/\" target=\"_blank\" rel=\"noreferrer noopener\">usar a IA para disparar lembretes<\/a>, integrar a aprendizagem aos fluxos do dia a dia e apoiar experi\u00eancias pr\u00e1ticas por meio de <a href=\"https:\/\/degreed.com\/experience\/blog\/degreed-maestro-ai-driven-coaching-for-your-whole-workforce\/\" target=\"_blank\" rel=\"noreferrer noopener\">coaching<\/a>, <a href=\"https:\/\/degreed.com\/experience\/blog\/degreed-maestro-ai-purpose-built-for-learning\/\" target=\"_blank\" rel=\"noreferrer noopener\">simula\u00e7\u00f5es<\/a> e <a href=\"https:\/\/degreed.com\/experience\/pt-br\/blog\/degreed-maestro-skill-assessment-personalized-learning\/\" target=\"_blank\" rel=\"noreferrer noopener\">orienta\u00e7\u00f5es com base em fun\u00e7\u00f5es<\/a>. A tecnologia deve servir para reduzir o estresse e trazer a aprendizagem para o fluxo de trabalho \u2014 em larga escala e de maneira precisa.<br \/><\/li>\n\n\n\n<li><strong>O ambiente de aprendizagem:<\/strong> um ambiente robusto de aprendizagem desenvolve <a href=\"https:\/\/degreed.com\/experience\/blog\/psychological-safety-at-work-the-big-role-it-can-play\/\" target=\"_blank\" rel=\"noreferrer noopener\">seguran\u00e7a psicol\u00f3gica<\/a>, estimula a experimenta\u00e7\u00e3o e trata o desenvolvimento de habilidades como uma prioridade cont\u00ednua. Ele floresce com aprendizagem colaborativa e feedback. Organiza\u00e7\u00f5es que fomentam esse tipo de ambiente contam com colaboradores mais autoconfiantes para usar a IA generativa. Sem isso, nem mesmo as ferramentas mais avan\u00e7adas combinadas com as melhores das inten\u00e7\u00f5es d\u00e3o conta do recado.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Esses facilitadores s\u00e3o interdependentes. Quando todos eles est\u00e3o presentes, as organiza\u00e7\u00f5es aceleram a ado\u00e7\u00e3o da tecnologia, diminuem o medo entre os colaboradores e transformam a aprendizagem em um motor estrat\u00e9gico do crescimento.<\/p>\n\n<p class=\"wp-block-paragraph\">\u201cA flu\u00eancia em IA n\u00e3o se limita \u00e0 aprendizagem individual\u201d, observa Tenorio. \u201cEla fica mais intensa quando h\u00e1 apoio, infraestrutura e preparo.\u201d<\/p>\n\n<h2 class=\"wp-block-heading\">Barreiras que sufocam o progresso<\/h2>\n\n<p class=\"wp-block-paragraph\">Hoje, <strong>73% dos executivos e diretores n\u00e3o t\u00eam nenhum treinamento formal em IA generativa<\/strong>. Com o alto escal\u00e3o navegando \u00e0s cegas nos mares da IA generativa, \u00e9 normal que haja uma estagna\u00e7\u00e3o nos investimentos e menos apetite para assumir riscos. Nessa linha, <strong>apenas uma em dez empresas financiam a aprendizagem de IA no n\u00edvel que uma transforma\u00e7\u00e3o verdadeira demanda<\/strong>.<\/p>\n\n<p class=\"wp-block-paragraph\">Mesmo quando h\u00e1 inten\u00e7\u00e3o estrat\u00e9gica, muitas empresas se deparam com obst\u00e1culos. Falta de direcionamento, escassez de recursos e temor de mudan\u00e7as continuam sufocando o progresso.<\/p>\n\n<p class=\"wp-block-paragraph\">Para l\u00edderes de RH e T&D, tudo isso \u00e9 uma deixa para assumir o controle, uma permiss\u00e3o para resolver o problema de confian\u00e7a da lideran\u00e7a e montar a infraestrutura de aprendizagem que potencializa a produtividade e a inova\u00e7\u00e3o com a IA generativa.<\/p>\n\n<h2 class=\"wp-block-heading\">Por que investir na flu\u00eancia em IA agora<\/h2>\n\n<p class=\"wp-block-paragraph\">A IA est\u00e1 evoluindo a passos largos. Al\u00e9m de se expor a riscos, quem demorar para adquirir flu\u00eancia nessa tecnologia pode perder a oportunidade de conquistar o engajamento dos melhores talentos, acelerar a produtividade e ganhar agilidade nos neg\u00f3cios.<\/p>\n\n<p class=\"wp-block-paragraph\">A aprendizagem precisa ser reenquadrada como uma \u00e1rea funcional fundamental da empresa \u2014 uma ferramenta de viabiliza\u00e7\u00e3o da transforma\u00e7\u00e3o, n\u00e3o uma rea\u00e7\u00e3o a novos paradigmas. Para l\u00edderes \u00e0 frente de mudan\u00e7as constantes, a flu\u00eancia \u00e9 mais do que uma capacidade;  \u00e9 um al\u00edvio.<\/p>\n\n<p class=\"wp-block-paragraph\">Em nosso estudo, <strong>um ter\u00e7o dos participantes relatam que o uso da IA generativa melhora expressivamente o desempenho de suas equipes. Quase 8 em cada 10 profissionais afirmam que a IA generativa abre espa\u00e7o para que eles se concentrem em tarefas estrat\u00e9gicas mais complexas. E 53% deles se sentem mais bem preparados para resolver problemas de neg\u00f3cios<\/strong>.<\/p>\n\n<p class=\"wp-block-paragraph\">Ademais, a mobilidade interna est\u00e1 despontando como um poderoso incentivo. Colaboradores que vislumbram a possibilidade de crescimento em suas fun\u00e7\u00f5es t\u00eam muito mais chances de permanecer na empresa. Ao apoiar o upskilling, o dom\u00ednio da IA e o desenvolvimento personalizado, as organiza\u00e7\u00f5es podem reduzir pedidos de demiss\u00f5es, elevar o moral e aproveitar ao m\u00e1ximo seus investimentos no desenvolvimento de talentos.<\/p>\n\n<h2 class=\"wp-block-heading\">Como grandes empresas est\u00e3o promovendo a flu\u00eancia em IA em larga escala<\/h2>\n\n<p class=\"wp-block-paragraph\">As empresas que est\u00e3o conquistando progressos significativos t\u00eam um ponto em comum: come\u00e7am com um claro alinhamento da lideran\u00e7a e, em seguida, escalam com prop\u00f3sito.<\/p>\n\n<p class=\"wp-block-paragraph\">Peguemos o exemplo de uma l\u00edder europeia do setor de alimentos e bebidas com centenas de f\u00e1bricas e milhares de marcas. Sua jornada de IA generativa nasceu na diretoria, com \u201cbootcamps\u201d em que executivos desenvolviam prot\u00f3tipos de produtos utilizando oito ferramentas de IA. Essa experi\u00eancia do alto escal\u00e3o gerou academias multidisciplinares que encurtaram o ciclo de decis\u00f5es de prototipagem de produtos de quase seis meses para apenas dois dias, provando o ROI de um m\u00e9todo \u201cTest & Learn\u201d que aumenta a autoconfian\u00e7a no uso da IA generativa.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Clientes em todos os setores contam com a Degreed para escalar a aprendizagem com velocidade.<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Vejamos o caso da Ericsson. Cinco anos atr\u00e1s, a gigante das telecomunica\u00e7\u00f5es come\u00e7ou a promover o upskilling de um grupo relativamente pequeno de 300 cientistas, para que adotassem a intelig\u00eancia artificial. <a href=\"https:\/\/degreed.com\/experience\/blog\/we-refuse-to-act-our-age-how-ericsson-puts-skills-to-work\/\" target=\"_blank\" rel=\"noreferrer noopener\">Agora, mais de 30 mil dos mais de 100 mil colaboradores da empresa s\u00e3o considerados <em>muito proficientes<\/em> em IA<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/degreed.com\/experience\/pt-br\/blog\/these-learning-leaders-are-redefining-workforce-development\/\" target=\"_blank\" rel=\"noreferrer noopener\">A Capgemini se viu diante de um desafio duplo:<\/a> desenvolver uma for\u00e7a de trabalho preparada para auxiliar os clientes a colocar a IA generativa em a\u00e7\u00e3o e integrar recursos de IA em opera\u00e7\u00f5es internas. Desenvolvido e implantado em apenas 10 semanas, seu <em>Campus de IA Generativa<\/em>, utilizando tecnologia da Degreed, disponibilizou treinamento em IA para os 340 mil colaboradores da Capgemini em todo o mundo, oferecendo a eles tudo o que precisavam para atender \u00e0s demandas de IA de iniciativas internas e externas. Com isso, impressionantes 91 mil colaboradores fizeram treinamentos sobre ferramentas de IA em apenas seis meses.<\/p>\n\n<h2 class=\"wp-block-heading\">A transforma\u00e7\u00e3o da aprendizagem em um ativo estrat\u00e9gico<\/h2>\n\n<p class=\"wp-block-paragraph\">\u00c9 muito comum vermos a aprendizagem ser tratada como uma fun\u00e7\u00e3o isolada. No entanto, ela passa a ser um motor de crescimento se for <a href=\"https:\/\/degreed.com\/experience\/success-stories\/workforce-skill-development-capgemini\/\" target=\"_blank\" rel=\"noreferrer noopener\">incorporada a todo o ciclo de vida dos colaboradores<\/a> \u2014 da integra\u00e7\u00e3o ao desenvolvimento de lideran\u00e7a. Ferramentas como a Degreed auxiliam equipes de RH e T&D a transformar insights em a\u00e7\u00f5es por meio da identifica\u00e7\u00e3o de lacunas de habilidades, personaliza\u00e7\u00e3o de trilhas e monitoramento do progresso em tempo real.<\/p>\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/degreed.com\/experience\/pt-br\/s\/?_category=ai-innovation-in-learning&_post_type=post\" target=\"_blank\" rel=\" noreferrer noopener\"><img decoding=\"async\" src=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/07\/May-20-2025-CTA-banners_pt_BR_CTA-1280x333-1-1024x267.png\" alt=\"\" class=\"wp-image-85106\" \/><\/a><\/figure>\n\n<h2 class=\"wp-block-heading\">O futuro<\/h2>\n\n<p class=\"wp-block-paragraph\">A transforma\u00e7\u00e3o da for\u00e7a de trabalho n\u00e3o come\u00e7a com uma plataforma. Tudo come\u00e7a com um prop\u00f3sito.<\/p>\n\n<p class=\"wp-block-paragraph\">O que define o sucesso da for\u00e7a de trabalho da sua organiza\u00e7\u00e3o? O que \u00e9 preciso para voc\u00eas chegarem l\u00e1? Para organiza\u00e7\u00f5es que priorizam agilidade, engajamento e resili\u00eancia, a resposta \u00e9 simples: aprendizagem.<\/p>\n\n<p class=\"wp-block-paragraph\">A Degreed ocupa uma posi\u00e7\u00e3o privilegiada para <a href=\"https:\/\/degreed.com\/experience\/pt-br\/blog\/more-speed-less-cost-bigger-impact-learning-in-an-ai-world\/\" target=\"_blank\" rel=\"noreferrer noopener\">transformar a aprendizagem na vantagem competitiva da sua organiza\u00e7\u00e3o<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\">Com a Degreed, sua organiza\u00e7\u00e3o:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Identifica necessidades<\/strong> utilizando dados e IA para detectar lacunas de habilidades e prioridades.<\/li>\n\n\n\n<li><strong>Personaliza o desenvolvimento<\/strong> por meio de experi\u00eancias de aprendizagem automatizadas que passaram por processos de curadoria.<\/li>\n\n\n\n<li><strong>Mensura mudan\u00e7as<\/strong> com m\u00e9tricas claras e confi\u00e1veis que demonstram os impactos da aprendizagem.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Em um mundo que est\u00e1 sempre mudando, a aprendizagem n\u00e3o est\u00e1 ligada apenas \u00e0 evolu\u00e7\u00e3o das pessoas, mas tamb\u00e9m aos sucessos das empresas.<\/p>\n\n<h2 class=\"wp-block-heading\">Aprofunde-se<\/h2>\n\n<p class=\"wp-block-paragraph\">Esteja entre os primeiros a <a href=\"https:\/\/get.degreed.com\/how-the-workforce-learns-2025-pre-release\" target=\"_blank\" rel=\"noreferrer noopener\">ter acesso ao nosso relat\u00f3rio <em>Como a for\u00e7a de trabalho aprende GenAI em 2025<\/em><\/a>, repleto de dados que ajudar\u00e3o a sua empresa a ter confian\u00e7a para liderar na era da IA.<\/p>\n\n<p class=\"wp-block-paragraph\">Quer saber ainda mais? Vamos bater um papo sobre como promover a flu\u00eancia em IA em larga escala em toda a sua organiza\u00e7\u00e3o.<\/p>\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/degreed.com\/experience\/pt-br\/request-demo\/\" target=\"_blank\" rel=\" noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"200\" src=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/Demo-CTA-1280x250-2-1024x200.png\" alt=\"\" class=\"wp-image-84855\" \/><\/a><\/figure>\n\n<p class=\"wp-block-paragraph\"><br \/><br \/><\/p>\n\n<p class=\"wp-block-paragraph\"><br \/><br \/><br \/><\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fique por dentro de insights estrat\u00e9gicos sobre como alcan\u00e7ar a flu\u00eancia em IA com aprendizagem personalizada, apoio da lideran\u00e7a e ferramentas escal\u00e1veis.<\/p>\n","protected":false},"author":129,"featured_media":85319,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[673,633],"tags":[809],"post_folder":[],"class_list":["post-86148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-learning-development-strategy","category-ai-innovation-in-learning","tag-como-a-forca-de-trabalho-aprende"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Como a for\u00e7a de trabalho aprende GenIA: o que 2.700 l\u00edderes t\u00eam a dizer - Degreed<\/title>\n<meta name=\"description\" content=\"Fique por dentro de insights estrat\u00e9gicos sobre como alcan\u00e7ar a flu\u00eancia em IA com aprendizagem personalizada, apoio da lideran\u00e7a e ferramentas escal\u00e1veis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como a for\u00e7a de trabalho aprende GenIA: o que 2.700 l\u00edderes t\u00eam a dizer\" \/>\n<meta property=\"og:description\" content=\"Fique por dentro de insights estrat\u00e9gicos sobre como alcan\u00e7ar a flu\u00eancia em IA com aprendizagem personalizada, apoio da lideran\u00e7a e ferramentas escal\u00e1veis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/\" \/>\n<meta property=\"og:site_name\" content=\"Degreed\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DegreedOfficial\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-29T16:37:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T21:06:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/05-28-25-Post-LENS-Gen-AI-Learning-Insights-from-HBP-Blog-Header-1200x1200-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tom Schultz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@degreed\" \/>\n<meta name=\"twitter:site\" content=\"@degreed\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tom Schultz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/blog\\\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/blog\\\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\\\/\"},\"author\":{\"name\":\"Tom Schultz\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/#\\\/schema\\\/person\\\/d9c7959382404452e07d2719f8e3f40e\"},\"headline\":\"Como a for\u00e7a de trabalho aprende GenIA: o que 2.700 l\u00edderes t\u00eam a dizer\",\"datePublished\":\"2025-05-29T16:37:03+00:00\",\"dateModified\":\"2025-12-16T21:06:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/blog\\\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\\\/\"},\"wordCount\":1793,\"publisher\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/blog\\\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/05-28-25-Post-LENS-Gen-AI-Learning-Insights-from-HBP-Blog-Header-1200x1200-1.png\",\"keywords\":[\"Como a for\u00e7a de trabalho aprende\"],\"articleSection\":[\"Estrat\u00e9gia de aprendizagem e desenvolvimento\u00a0\",\"IA e inova\u00e7\u00e3o em aprendizagem\u00a0\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/blog\\\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\\\/\",\"url\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/blog\\\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\\\/\",\"name\":\"Como a for\u00e7a de trabalho aprende GenIA: o que 2.700 l\u00edderes t\u00eam a dizer - Degreed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/blog\\\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/blog\\\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/05-28-25-Post-LENS-Gen-AI-Learning-Insights-from-HBP-Blog-Header-1200x1200-1.png\",\"datePublished\":\"2025-05-29T16:37:03+00:00\",\"dateModified\":\"2025-12-16T21:06:43+00:00\",\"description\":\"Fique por dentro de insights estrat\u00e9gicos sobre como alcan\u00e7ar a flu\u00eancia em IA com aprendizagem personalizada, apoio da lideran\u00e7a e ferramentas escal\u00e1veis.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/blog\\\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/blog\\\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/blog\\\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\\\/#primaryimage\",\"url\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/05-28-25-Post-LENS-Gen-AI-Learning-Insights-from-HBP-Blog-Header-1200x1200-1.png\",\"contentUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/05-28-25-Post-LENS-Gen-AI-Learning-Insights-from-HBP-Blog-Header-1200x1200-1.png\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/blog\\\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como a for\u00e7a de trabalho aprende GenIA: o que 2.700 l\u00edderes t\u00eam a dizer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/#website\",\"url\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/\",\"name\":\"Degreed\",\"description\":\"The Learning and Upskilling Platform\",\"publisher\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/#organization\",\"name\":\"Degreed\",\"url\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/logo.svg\",\"caption\":\"Degreed\"},\"image\":{\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DegreedOfficial\",\"https:\\\/\\\/x.com\\\/degreed\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/degreed\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkH3pyPKVngvsZzZlmoH-Mw\",\"https:\\\/\\\/www.instagram.com\\\/degreed\\\/\"],\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"201\",\"maxValue\":\"500\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/degreed.com\\\/experience\\\/pt-br\\\/#\\\/schema\\\/person\\\/d9c7959382404452e07d2719f8e3f40e\",\"name\":\"Tom Schultz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-tom-schultz-96x96.png\",\"url\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-tom-schultz-96x96.png\",\"contentUrl\":\"https:\\\/\\\/explore.degreed.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-tom-schultz-96x96.png\",\"caption\":\"Tom Schultz\"},\"description\":\"Tom Schultz is the senior writer and editor at Degreed.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Como a for\u00e7a de trabalho aprende GenIA: o que 2.700 l\u00edderes t\u00eam a dizer - Degreed","description":"Fique por dentro de insights estrat\u00e9gicos sobre como alcan\u00e7ar a flu\u00eancia em IA com aprendizagem personalizada, apoio da lideran\u00e7a e ferramentas escal\u00e1veis.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/","og_locale":"pt_BR","og_type":"article","og_title":"Como a for\u00e7a de trabalho aprende GenIA: o que 2.700 l\u00edderes t\u00eam a dizer","og_description":"Fique por dentro de insights estrat\u00e9gicos sobre como alcan\u00e7ar a flu\u00eancia em IA com aprendizagem personalizada, apoio da lideran\u00e7a e ferramentas escal\u00e1veis.","og_url":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/","og_site_name":"Degreed","article_publisher":"https:\/\/www.facebook.com\/DegreedOfficial","article_published_time":"2025-05-29T16:37:03+00:00","article_modified_time":"2025-12-16T21:06:43+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/05-28-25-Post-LENS-Gen-AI-Learning-Insights-from-HBP-Blog-Header-1200x1200-1.png","type":"image\/png"}],"author":"Tom Schultz","twitter_card":"summary_large_image","twitter_creator":"@degreed","twitter_site":"@degreed","twitter_misc":{"Escrito por":"Tom Schultz","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/#article","isPartOf":{"@id":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/"},"author":{"name":"Tom Schultz","@id":"https:\/\/degreed.com\/experience\/pt-br\/#\/schema\/person\/d9c7959382404452e07d2719f8e3f40e"},"headline":"Como a for\u00e7a de trabalho aprende GenIA: o que 2.700 l\u00edderes t\u00eam a dizer","datePublished":"2025-05-29T16:37:03+00:00","dateModified":"2025-12-16T21:06:43+00:00","mainEntityOfPage":{"@id":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/"},"wordCount":1793,"publisher":{"@id":"https:\/\/degreed.com\/experience\/pt-br\/#organization"},"image":{"@id":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/#primaryimage"},"thumbnailUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/05-28-25-Post-LENS-Gen-AI-Learning-Insights-from-HBP-Blog-Header-1200x1200-1.png","keywords":["Como a for\u00e7a de trabalho aprende"],"articleSection":["Estrat\u00e9gia de aprendizagem e desenvolvimento\u00a0","IA e inova\u00e7\u00e3o em aprendizagem\u00a0"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/","url":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/","name":"Como a for\u00e7a de trabalho aprende GenIA: o que 2.700 l\u00edderes t\u00eam a dizer - Degreed","isPartOf":{"@id":"https:\/\/degreed.com\/experience\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/#primaryimage"},"image":{"@id":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/#primaryimage"},"thumbnailUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/05-28-25-Post-LENS-Gen-AI-Learning-Insights-from-HBP-Blog-Header-1200x1200-1.png","datePublished":"2025-05-29T16:37:03+00:00","dateModified":"2025-12-16T21:06:43+00:00","description":"Fique por dentro de insights estrat\u00e9gicos sobre como alcan\u00e7ar a flu\u00eancia em IA com aprendizagem personalizada, apoio da lideran\u00e7a e ferramentas escal\u00e1veis.","breadcrumb":{"@id":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/#primaryimage","url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/05-28-25-Post-LENS-Gen-AI-Learning-Insights-from-HBP-Blog-Header-1200x1200-1.png","contentUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/05-28-25-Post-LENS-Gen-AI-Learning-Insights-from-HBP-Blog-Header-1200x1200-1.png","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/degreed.com\/experience\/pt-br\/blog\/how-the-workforce-learns-gen-ai-see-what-2700-leaders-say\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/degreed.com\/experience\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Como a for\u00e7a de trabalho aprende GenIA: o que 2.700 l\u00edderes t\u00eam a dizer"}]},{"@type":"WebSite","@id":"https:\/\/degreed.com\/experience\/pt-br\/#website","url":"https:\/\/degreed.com\/experience\/pt-br\/","name":"Degreed","description":"The Learning and Upskilling Platform","publisher":{"@id":"https:\/\/degreed.com\/experience\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/degreed.com\/experience\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/degreed.com\/experience\/pt-br\/#organization","name":"Degreed","url":"https:\/\/degreed.com\/experience\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/degreed.com\/experience\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2023\/05\/logo.svg","contentUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2023\/05\/logo.svg","caption":"Degreed"},"image":{"@id":"https:\/\/degreed.com\/experience\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DegreedOfficial","https:\/\/x.com\/degreed","https:\/\/www.linkedin.com\/company\/degreed\/","https:\/\/www.youtube.com\/channel\/UCkH3pyPKVngvsZzZlmoH-Mw","https:\/\/www.instagram.com\/degreed\/"],"numberOfEmployees":{"@type":"QuantitativeValue","minValue":"201","maxValue":"500"}},{"@type":"Person","@id":"https:\/\/degreed.com\/experience\/pt-br\/#\/schema\/person\/d9c7959382404452e07d2719f8e3f40e","name":"Tom Schultz","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/cropped-tom-schultz-96x96.png","url":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/cropped-tom-schultz-96x96.png","contentUrl":"https:\/\/explore.degreed.com\/wp-content\/uploads\/2025\/05\/cropped-tom-schultz-96x96.png","caption":"Tom Schultz"},"description":"Tom Schultz is the senior writer and editor at Degreed."}]}},"_links":{"self":[{"href":"https:\/\/explore.degreed.com\/experience\/pt-br\/wp-json\/wp\/v2\/posts\/86148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/explore.degreed.com\/experience\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/explore.degreed.com\/experience\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/pt-br\/wp-json\/wp\/v2\/users\/129"}],"replies":[{"embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/pt-br\/wp-json\/wp\/v2\/comments?post=86148"}],"version-history":[{"count":0,"href":"https:\/\/explore.degreed.com\/experience\/pt-br\/wp-json\/wp\/v2\/posts\/86148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/pt-br\/wp-json\/wp\/v2\/media\/85319"}],"wp:attachment":[{"href":"https:\/\/explore.degreed.com\/experience\/pt-br\/wp-json\/wp\/v2\/media?parent=86148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/pt-br\/wp-json\/wp\/v2\/categories?post=86148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/pt-br\/wp-json\/wp\/v2\/tags?post=86148"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/explore.degreed.com\/experience\/pt-br\/wp-json\/wp\/v2\/post_folder?post=86148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}